{"id":4073,"date":"2023-07-11T15:20:35","date_gmt":"2023-07-11T13:20:35","guid":{"rendered":"https:\/\/beta.persolog.de\/?page_id=4073"},"modified":"2026-04-14T12:07:28","modified_gmt":"2026-04-14T10:07:28","slug":"allgemeine-geschaeftsbedingungen","status":"publish","type":"page","link":"https:\/\/persolog.com\/de\/general-terms-conditions\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4073\" class=\"elementor elementor-4073\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c14e34b e-flex e-con-boxed e-con e-parent\" data-id=\"c14e34b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c468b83 elementor-widget elementor-widget-spacer\" data-id=\"c468b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fbb77c e-flex e-con-boxed e-con e-parent\" data-id=\"5fbb77c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c599e5d elementor-widget elementor-widget-heading\" data-id=\"c599e5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Allgemeine Gesch\u00e4ftsbedingungen f\u00fcr Bestellungen und Buchungen bei der persolog GmbH f\u00fcr Verbraucher und Unternehmen\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abc1125 e-flex e-con-boxed e-con e-parent\" data-id=\"abc1125\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3ce425 elementor-widget elementor-widget-text-editor\" data-id=\"a3ce425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stand: 01.09.2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5dcf42 e-flex e-con-boxed e-con e-parent\" data-id=\"e5dcf42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed4c6d elementor-widget elementor-widget-spacer\" data-id=\"2ed4c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b57427 e-flex e-con-boxed e-con e-parent\" data-id=\"9b57427\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e0e1581 e-flex e-con-boxed e-con e-child\" data-id=\"e0e1581\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9389ff8 elementor-widget elementor-widget-heading\" data-id=\"9389ff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">I. Geltungsbereich<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57859b7 e-flex e-con-boxed e-con e-parent\" data-id=\"57859b7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-439c7a2 elementor-widget elementor-widget-text-editor\" data-id=\"439c7a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>F\u00fcr s\u00e4mtliche Angebote, Lieferungen und sonstigen Leistungen im Hinblick auf Bestellungen\/Buchungen von Waren bei uns gelten die nachfolgenden Allgemeinen Gesch\u00e4ftsbedingungen (nachfolgend nur noch \u201eGesch\u00e4ftsbedingungen\u201c) in ihrer zum Zeitpunkt der Bestellung\/Buchung g\u00fcltigen Fassung.<\/li><\/ol><ol start=\"2\"><li>Waren im Sinne dieser Gesch\u00e4ftsbedingungen sind alle Produkte, Seminare und Leistungen, die im Rahmen einer Bestellung\/Buchung bei uns erworben\/gebucht werden k\u00f6nnen.<\/li><\/ol><ol start=\"3\"><li>Unsere Gesch\u00e4ftsbedingungen gelten ausschlie\u00dflich. Entgegenstehende, abweichende oder erg\u00e4nzenden Bedingungen des Vertragspartners\/Bestellers (nachfolgend nur noch \u201eKunde\u201c), erkennen wir nicht an, es sei denn, wir h\u00e4tten ausdr\u00fccklich schriftlich ihrer Geltung zugestimmt. Unsere Gesch\u00e4ftsbedingungen gelten auch dann, wenn wir in Kenntnis entgegenstehender oder abweichender Bedingungen des Kunden unsere Leistungen vorbehaltlos erbringen.<\/li><\/ol><ol start=\"4\"><li>Unsere Gesch\u00e4ftsbedingungen gelten sowohl gegen\u00fcber Verbrauchern als auch gegen\u00fcber Unternehmern, es sei denn, in der jeweiligen Klausel wird eine Differenzierung vorgenommen. Unternehmer im Sinne unserer Gesch\u00e4ftsbedingungen sind juristische Personen des \u00f6ffentlichen Rechts, ein \u00f6ffentlich-rechtliches Sonderverm\u00f6gen oder ein Unternehmer, der bei Abschluss des Vertrages in Aus\u00fcbung seiner gewerblichen oder selbstst\u00e4ndigen beruflichen T\u00e4tigkeit handelt (\u00a7 14 BGB). Verbraucher ist eine nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu einem Zweck abschlie\u00dft, der \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugeordnet werden kann (\u00a7 13 BGB).<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fa3e86 e-flex e-con-boxed e-con e-parent\" data-id=\"4fa3e86\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-301fe2c e-flex e-con-boxed e-con e-child\" data-id=\"301fe2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce8a604 elementor-widget elementor-widget-heading\" data-id=\"ce8a604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">II. Vertragsschluss<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04731db elementor-widget elementor-widget-text-editor\" data-id=\"04731db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Bei Bestellungen\/Buchungen \u00fcber unseren Online-Shop oder Landingpages stellen die Pr\u00e4sentation und Bewerbung von Waren in unserem Online-Shop kein verbindliches Angebot zum Abschluss eines Vertrages dar, sondern lediglich eine Einladung an den Kunden, ein verbindliches Angebot abzugeben. Der Kunde kann bei Verf\u00fcgbarkeit der Ware ein verbindliches Angebot zur Bestellung der im Warenkorb enthaltenen Waren erst nach Registrierung und erfolgreicher Einrichtung eines Kundenkontos nach Ziffer VI dieser Gesch\u00e4ftsbedingungen abgeben, indem er nach Durchlaufen des Online-Bestellvorgangs die Bestellung durch Aktivierung der Schaltfl\u00e4che \u201ezahlungspflichtig bestellen\u201c bzw. \u201ezahlungspflichtig anmelden\u201c absendet. Das Angebot kann nur abgegeben werden, wenn der Kunde zuvor durch Klicken auf den entsprechenden Button diese Gesch\u00e4ftsbedingungen akzeptiert und diese dadurch in sein Angebot aufgenommen hat. Wir schicken daraufhin dem Kunden eine Bestell-\/Buchungsbest\u00e4tigung per E-Mail zu. Die Bestell-\/Buchungsbest\u00e4tigung stellt die Annahme des Angebots dar. Bei Seminarbuchungen erh\u00e4lt der Kunde eine Buchungsbest\u00e4tigung, sofern Seminarpl\u00e4tze verf\u00fcgbar sind. Bei der Bestellung von Produkten ergibt sich aus der Bestellbest\u00e4tigung der Inhalt des Vertrages und der ungef\u00e4hre Liefertermin, sofern nach der Eigenschaft der gekauften Ware eine Lieferung erforderlich ist.<\/li><\/ol><ol start=\"2\"><li>Au\u00dferhalb von Bestellungen\/Buchungen in unserem Online-Shop stellen Anfragen des Kunden, m\u00fcndlich oder schriftlich, \u00fcber Telefon, Fax oder E-Mail, ein verbindliches Angebot zum Abschluss eines Vertrages dar. Wir erstellen daraufhin eine Bestell-\/Buchungsbest\u00e4tigung, die wir dem Kunden per E-Mail zuschicken. Die Bestell-\/Buchungsbest\u00e4tigung stellt die Annahme des Angebots dar. Bei Seminarbuchungen erh\u00e4lt der Kunde eine Buchungsbest\u00e4tigung, sofern Seminarpl\u00e4tze verf\u00fcgbar sind. Bei der Bestellung von Produkten ergibt sich aus der Bestellbest\u00e4tigung der Inhalt des Vertrages und der ungef\u00e4hre Liefertermin, sofern nach der Eigenschaft der gekauften Ware eine Lieferung erforderlich ist.<\/li><\/ol><ol start=\"3\"><li>Die in den Regelungen des \u00a7 312i Abs. 1 S. 1 Nr. 1 bis Nr. 3 und S. 2 BGB enthaltenen Pflichten werden ausgeschlossen.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cda8258 e-flex e-con-boxed e-con e-child\" data-id=\"cda8258\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b97efb5 e-flex e-con-boxed e-con e-child\" data-id=\"b97efb5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fbd7cd elementor-widget elementor-widget-heading\" data-id=\"1fbd7cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">III. Lieferung von Waren<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0c8e28 elementor-widget elementor-widget-text-editor\" data-id=\"e0c8e28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Sofern nach der Eigenschaft der gekauften Ware eine Lieferung erforderlich ist, berechnet sich die von uns in der Bestellbest\u00e4tigung angegebene Lieferzeit vom Zeitpunkt der Bestellbest\u00e4tigung.<\/li><li>Ist der Kunde Unternehmer, gelten erg\u00e4nzend nachfolgende Regelungen:<br \/>a. Liefertermin und Liefertermine gelten grunds\u00e4tzlich als ann\u00e4hernd. Sie sind eingehalten, wenn bis zu ihrem Ablauf die Ware versandt wurde.<br \/>b. Verlangt der Kunde nach Vertragsschluss \u00c4nderungen oder Erg\u00e4nzungen der Bestellung, welche die Einhaltung des Liefertermins unm\u00f6glich machen, so verl\u00e4ngert sich der Liefertermin entsprechend den \u00c4nderungen und Erg\u00e4nzungen um einen f\u00fcr die Durchf\u00fchrung dieser \u00c4nderungen und Erg\u00e4nzungen angemessenen Zeitraum.<br \/>c. F\u00fcr weitere Lieferungen steht uns so lange ein Zur\u00fcckbehaltungsrecht zu, bis s\u00e4mtliche vorhergehenden Lieferungen bezahlt sind.<br \/>d. Wenn der Kunde im Rahmen einer Bestellung mehrere Waren bestellt, f\u00fcr die unterschiedliche Lieferzeiten gelten, versenden wir die Waren (sofern nicht anders vereinbart) in einer gemeinsamen Lieferung. In diesem Fall gilt f\u00fcr die Warenbestellung insgesamt die Lieferzeit, die f\u00fcr die Ware mit der l\u00e4ngsten Lieferzeit gilt.<br \/>e. Bei der Lieferung von Waren sind wir berechtigt, in zumutbarem Umfang Teillieferungen vorzunehmen und diese gesondert zu berechnen.<br \/>f. Mit der \u00dcbergabe der Ware an das Versandunternehmen geht die Gefahr auf den Kunden \u00fcber. Der Versand erfolgt stets im Auftrag des Kunden.<\/li><li>Sofern wir verbindliche Lieferfristen aus Gr\u00fcnden, die wir nicht zu vertreten haben, nicht einhalten k\u00f6nnen (Nichtverf\u00fcgbarkeit der Ware), werden wir den K\u00e4ufer hier\u00fcber unverz\u00fcglich informieren und gleichzeitig die voraussichtliche, neue Lieferfrist mitteilen. Ist die Ware auch innerhalb der neuen Lieferfrist nicht verf\u00fcgbar, sind wir berechtigt, ganz oder teilweise vom Vertrag zur\u00fcckzutreten; eine bereits erbrachte Gegenleistung des Kunden erstatten wir dem Kunden unverz\u00fcglich. Als Fall der Nichtverf\u00fcgbarkeit der Ware in diesem Sinne gilt insbesondere die nicht rechtzeitige Selbstbelieferung durch Zulieferer, wenn wir ein kongruentes Deckungsgesch\u00e4ft abgeschlossen haben, weder uns und noch unserer Zulieferer ein Verschulden trifft oder wir im Einzelfall zur Beschaffung nicht verpflichtet sind.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-300a729 e-flex e-con-boxed e-con e-parent\" data-id=\"300a729\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4cb1b2d e-flex e-con-boxed e-con e-child\" data-id=\"4cb1b2d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3de73ec e-flex e-con-boxed e-con e-child\" data-id=\"3de73ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34550e8 elementor-widget elementor-widget-heading\" data-id=\"34550e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">IV. Buchung von Seminaren<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffb941e elementor-widget elementor-widget-text-editor\" data-id=\"ffb941e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Folgende Seminartypen werden von persolog angeboten:<ol><li><strong>Gruppenseminare<\/strong> und <strong>Inhouse-Seminaren<\/strong>: <br \/>Seminare werden entweder als offene <strong style=\"font-size: 16px;\">Gruppenseminare<\/strong><span style=\"font-size: 16px;\"> oder als individuell an den Kundenanforderungen ausgerichtete, in geschlossenen Gruppen stattfindende und ausschlie\u00dflich von <\/span><strong style=\"font-size: 16px;\">Unternehmen<\/strong><span style=\"font-size: 16px;\">buchbare Inhouse-Seminare angeboten. Offene Seminare und Inhouse-Seminare finden jeweils als Pr\u00e4senzseminare oder als per Video mit der Software \u201eZoom\u201c oder einem vergleichbaren Tool \u00fcbertragene Online-Seminare statt.<\/span><\/li><li><strong>Digitale Seminare<\/strong>:<br \/>\u00dcber unsere E-Learning-Plattform \u201epersolog Academy\u201c bieten wir erg\u00e4nzend Seminare sowie Fortbildungen und Schulungen an, die der Kunde bzw. Teilnehmer jederzeit online beginnen und durchf\u00fchren kann (nachfolgend nur \u201edigitale Seminare\u201c)<\/li><li><strong>Blended-Learning-Seminare<\/strong>:<br \/>Zus\u00e4tzlich bieten wir Kurse nach dem \u201eBlended-Learning-Konzept\u201c als Kombi-nation aus digitalen Seminaren und Online-Seminaren bzw. Pr\u00e4senzseminaren an (nachfolgend nur noch \u201eBlended-Learning-Seminare\u201c).<\/li><\/ol><\/li><\/ol><ol start=\"2\"><li>Die Zielgruppe und der Inhalt der einzelnen Seminare sowie die jeweiligen Leistungen, die in deren Rahmen erbracht werden, sind der jeweiligen Seminar- oder Programmbeschreibung zu entnehmen. Begleitende Seminarunterlagen werden an den Kunden bzw. Teilnehmer in Papierform ausgegeben bzw. in elektronischer Form \u00fcbersandt, sofern sich dies ausdr\u00fccklich aus der jeweiligen Seminarbeschreibung ergibt. Werden Seminarunterlagen ausgegeben bzw. \u00fcbersandt, so erfolgt dies in der Regel vor oder bei Beginn des Seminars, in Einzelf\u00e4llen auch w\u00e4hrend oder am Ende des Seminars.<\/li><li>Ggf. erforderliche An- und Abreisen zu Seminaren sind vom Kunden auf eigene Kosten zu organisieren.<\/li><li>Die Verpflegung von Kunden oder Teilnehmern w\u00e4hrend der Seminarpausen (z. B. Snacks, Getr\u00e4nke) ist im Seminarpreis enthalten, sofern dies in der Seminarbeschreibung ausdr\u00fccklich angegeben ist.<\/li><li>Sofern und soweit dies in der Seminarbeschreibung ausdr\u00fccklich angegeben ist, erh\u00e4lt der Kunde bzw. Teilnehmer nach der Teilnahme am Seminar eine Teilnahmebescheinigung. Die Teilnahmebescheinigung wird dem Kunden bzw. Teilnehmer am Ende des Seminars entweder elektronisch oder in Papierform ausgeh\u00e4ndigt, in elektronischer Form innerhalb von 7 Werktagen an die vom Kunden bzw. Teilnehmer bei der Buchung angegebene E-Mail-Adresse gesendet bzw als Download zur Verf\u00fcgung gestellt.<\/li><li>Bei Pr\u00e4senz- oder Online-Seminaren behalten wir uns das Recht vor, die Buchungsbest\u00e4tigung einseitig zu widerrufen und das Seminar abzusagen oder zu verlegen. In diesem Fall kann der Teilnehmende bzw. der Kunde an einem alternativen Termin\/Seminar teilnehmen oder die Buchung stornieren. Bei Stornierung erstatten wir dem Kunden den bereits gezahlten Seminarpreis. Weitere Anspr\u00fcche sind ausgeschlossen.<\/li><li>Ein Rechtsanspruch auf die Leitung des gebuchten Seminars durch den in der Seminarbeschreibung genannten Referenten besteht nicht. Wir behalten uns das Recht vor, den benannten Referenten aus gegebenen Gr\u00fcnden, wie z. B. Krankheit oder anderen Verhinderungsgr\u00fcnden, durch einen anderen unserer Referenten zu ersetzen.<\/li><li>Bei Pr\u00e4senzseminaren oder Online-Seminaren ist der mit Vertragsschluss erworbene Anspruch auf Teilnahme an unseren Seminaren nicht \u00fcbertragbar. Bei digitalen Seminaren und Blended-Learning-Seminaren erh\u00e4lt jeder Kunde bzw. Teilnehmer von uns einen pers\u00f6nlichen Zugang. Die Nutzung der Inhalte unserer E-Learning-Plattform ist auf diesen Kunden bzw. Teilnehmer und auf den in der Seminarbeschreibung angegebenen Zeitraum beschr\u00e4nkt. Eine Weitergabe der Zugangsdaten an Dritte, die von uns keinen pers\u00f6nlichen Zugang erhalten haben, ist nicht gestattet.<\/li><li>Wir sind berechtigt, unsere Pr\u00e4senzseminare als Online-Seminare durchzuf\u00fchren, wenn die Durchf\u00fchrung von Pr\u00e4senzseminaren durch beh\u00f6rdliche Anordnungen eingeschr\u00e4nkt oder untersagt wird. In diesem Fall hat der Kunde ausschlie\u00dflich die Wahl, das Pr\u00e4senzseminar auf einen sp\u00e4teren Termin umzubuchen oder an dem das Pr\u00e4senzseminar ersetzenden Online-Seminar teilzunehmen. Ein Anspruch des Kunden auf eine kostenfreie Stornierung des Seminars besteht nicht. \u00dcber den Wechsel vom Pr\u00e4senzseminar zum Online-Seminar wird der Kunde vor dem gebuchten Termin informiert. Die Entscheidung zur Teilnahme am Online-Seminar gilt als getroffen, wenn der Kunde nicht 48 Stunden vor Beginn des Online-Seminars eine Umbuchung per E-Mail beantragt<\/li><li>Im Falle der Teilnahme an einem Online-Seminar erh\u00e4lt der Kunde bzw. Teilnehmer nach Zahlung des Seminarpreises sp\u00e4testens am Vortag per E-Mail weitere Informationen \u00fcber die technischen Voraussetzungen, die die Hard- und Software erf\u00fcllen muss notwendige Hinweise zur Nutzung von \u201eZoom\u201c oder einem vergleichbaren Tool, der geplante Zeitpunkt des Online-Seminars und der Zugangscode, der es dem Kunden oder Teilnehmer erm\u00f6glicht, das Online-Seminar in Echtzeit auf einem internetf\u00e4higen Endger\u00e4t (PC, Laptop) zu verfolgen , Smartphone, Tablet). Hierzu muss der Kunde bzw. Teilnehmer vorab die \u201eZoom-App\u201c bzw. das \u201eZoom-Programm\u201c oder ein vergleichbares Tool herunterladen. Die Erstellung eines Zoom-Kontos durch den Kunden bzw. Teilnehmer ist nicht erforderlich, die Installation der Software auf seinem Endger\u00e4t gen\u00fcgt. Der Code ist ausschlie\u00dflich f\u00fcr den Kunden bzw. Teilnehmer bestimmt, darf nicht weitergegeben werden und berechtigt den Kunden bzw. Teilnehmer nur zum einmaligen Empfang der \u00dcbermittlung. Auch die Beteiligung Dritter an der \u00dcbertragung gemeinsam mit dem Kunden bzw. Abonnenten ist nicht gestattet. Im Falle eines Versto\u00dfes erlischt das Recht auf Teilnahme an der \u00dcbertragung; die Zahlungsverpflichtung bleibt jedoch bestehen. Gleiches gilt f\u00fcr Aufzeichnungen bzw. Aufzeichnungen der \u00dcbertragung in Ton und\/oder Bild und die Speicherung auf Datentr\u00e4gern. Sollte die \u00dcbertragung des Online-Seminars aufgrund unzureichender technischer Voraussetzungen oder fehlerhafter Bedienung des Kunden oder Teilnehmers nicht oder nicht ordnungsgem\u00e4\u00df m\u00f6glich sein, besteht ebenfalls kein Anspruch auf R\u00fcckerstattung oder erneute Teilnahme am n\u00e4chsten Online-Seminar zum gleichen Thema.<\/li><li>F\u00fcr die Dauer und Beendigung des Vertragsverh\u00e4ltnisses gelten folgende Regelungen:<ul><li class=\"translation-block\"><span style=\"font-style: inherit;font-weight: inherit;color: var( --e-global-color-text );background-color: var(--ast-global-color-5)\">Im Falle von <\/span><strong style=\"font-style: inherit;color: var( --e-global-color-text );background-color: var(--ast-global-color-5)\">Pr\u00e4senzseminaren<\/strong><span style=\"font-style: inherit;font-weight: inherit;color: var( --e-global-color-text );background-color: var(--ast-global-color-5)\"> und <\/span><strong style=\"font-style: inherit;color: var( --e-global-color-text );background-color: var(--ast-global-color-5)\">Online-Seminaren<\/strong><span style=\"font-style: inherit;font-weight: inherit;color: var( --e-global-color-text );background-color: var(--ast-global-color-5)\"> beinhaltet der Vertrag keine Mindestlaufzeit. Die Dauer des Vertragsverh\u00e4ltnisses richtet sich nach der Art oder dem Zweck der Leistung und endet automatisch mit dem jeweiligen Seminar ohne K\u00fcndigung gem\u00e4\u00df \u00a7620 (2) BGB. Das Recht zur au\u00dferordentlichen K\u00fcndigung bleibt unber\u00fchrt.<\/span><\/li><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Vertr\u00e4ge f\u00fcr <\/span><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">digitale Seminare<\/strong><span style=\"background-color: var(--ast-global-color-5); font-weight: inherit; font-style: inherit; color: var( --e-global-color-text );\"> beginnen mit Vertragsschluss und enden mit Ablauf der jeweiligen Seminarbeschreibung angegebene Laufzeit, ohne dass es einer K\u00fcndigung bedarf.\u00a0<\/span>der dem Wert unserer Leistungen w\u00e4hrend der Laufzeit des Vertrags entspricht. Das Recht zur au\u00dferordentlichen K\u00fcndigung sowie bei Verbrauchern das Recht zur Beendigung des Vertrages nach \u00a7\u00a7 327c, 327m, 327r BGB bleiben unber\u00fchrt.<\/li><li><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Blended-Learning-Seminare<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> unterfallen den Bestimmungen des Fernunterrichtsschutzgesetzes (FernUSG) und k\u00f6nnen vom Kunden erstmals zum Ablauf des ersten Halbjahres nach Vertragsschluss mit einer Frist von sechs Wochen gek\u00fcndigt werden, nach Ablauf des ersten Halbjahres ist eine K\u00fcndigung jederzeit mit einer Frist von drei Monaten gek\u00fcndigt werden. Die K\u00fcndigung bedarf der Textform. <\/span>Im Falle<span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">der K\u00fcndigung hat der Kunde nur den Anteil der Verg\u00fctung zu entrichten,\u00a0<\/span>der dem Wert unserer Leistungen w\u00e4hrend der Laufzeit des Vertrags entspricht. Das Recht zur au\u00dferordentlichen K\u00fcndigung sowie bei Verbrauchern das Recht zur Beendigung des Vertrages nach \u00a7\u00a7 327c, 327m, 327r BGB bleiben unber\u00fchrt.<\/li><\/ul><\/li><li>Im Hinblick auf Stornierungen und Umbuchungen von Seminaren gelten folgende Bestimmungen:<ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Buchungen von <\/span><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Pr\u00e4senzseminaren<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> (Gruppenseminare) k\u00f6nnen innerhalb von 14 Tagen nach Vertragsschluss ohne Angabe von Gr\u00fcnden storniert werden. Bei sp\u00e4teren Stornierungen ist der volle Seminarpreis f\u00e4llig. Der Eingang der Stornierungserkl\u00e4rung ist in Schriftform daf\u00fcr ma\u00dfgeblich. Alternativ kann der Kunde einen anderen Teilnehmenden benennen, um eine Stornierung zu vermeiden. Erfordert das Seminar eine vorherige Zertifizierung mit dem persolog\u00ae Pers\u00f6nlichkeits-Modell (oder einer anderen Zertifizierung der persolog GmbH), muss die Ersatzperson diese Voraussetzung erf\u00fcllen.<\/span><\/li><\/ul><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Der Kunde kann offene <\/span><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Pr\u00e4senzseminaren<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> (Gruppenseminare) 14 Tage nach Vertragsschluss kostenlos einen neuen Termin oder ein Seminar zu einem anderen Thema aussuchen (Umbuchung). Bei Umbuchungen von einem Seminar einer niedrigeren Preiskategorie in ein Seminar mit einer h\u00f6heren Preiskategorie, ist die Differenz zu begleichen. Ab 15 Tage nach Vertragsschluss bis 31 Tage vor Seminarbeginn berechnen wir bei einer Umbuchung eine Bearbeitungsgeb\u00fchr von 50 Euro pro Seminar. Bei sp\u00e4teren <\/span><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Umbuchungen<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> berechnen wir 10 % des Seminarpreises, mindestens aber 50 Euro pro Seminar. Sp\u00e4tere \u00c4nderungsw\u00fcnsche nehmen wir nicht an. Der Seminarpreis ist ab 14 Tage vor Seminarbeginn unabh\u00e4ngig von der Teilnahme an dem gebuchten Seminar zu bezahlen. Ma\u00dfgeblich ist jeweils der Tag, an dem die Erkl\u00e4rung des Kunden in Textform bei uns eingeht. Dem Kunden steht es frei, zur Abwendung einer Umbuchung einen anderen Teilnehmer zu benennen. Sofern f\u00fcr die Veranstaltung eine vorherige Zertifizierung mit dem persolog\u00ae Pers\u00f6nlichkeits-Modell (oder einer anderen Zertifizierung der persolog GmbH) erforderlich ist, muss die Ersatzperson diese Voraussetzung erf\u00fcllen.<\/span><\/li><\/ul><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Buchungen von <\/span><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Inhouse-Seminaren<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> (als Pr\u00e4senzseminare oder Online-Seminare) k\u00f6nnen bis 12 Wochen vor Seminarbeginn mit voller R\u00fcckerstattung des Seminarpreises storniert werden. Bei Stornierungen bis 8 Wochen vor Seminarbeginn berechnen wir eine Stornogeb\u00fchr von 25% des Seminarpreises, bei Stornierungen bis 6 Wochen vor Seminarbeginn eine Stornogeb\u00fchr von 50% des Seminarpreises und bei Stornierungen bis 4 Wochen vor Beginn 75% des Seminarpreises. Bei sp\u00e4teren Stornierungen ist der volle Seminarpreis zu zahlen. Der Nachweis eines h\u00f6heren Schadens bleibt uns vorbehalten, dem Kunden bleibt der Nachweis geringerer oder fehlender Kosten vorbehalten. Im \u00dcbrigen gelten die Regelungen der Ziffer 13.<\/span><\/li><\/ul><ul><li><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Inhouse-Seminare<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> (als Pr\u00e4senzseminare oder Online-Seminare) k\u00f6nnen bis 21 Tage vor Seminarbeginn kostenfrei umgebucht werden, nachdem die Parteien einen anderen Termin vereinbart haben. Bei einer sp\u00e4teren Umbuchung auf einen beiderseits vereinbarten Termin berechnen wir 25% des Seminarpreises. Der Nachweis eines h\u00f6heren Schadens bleibt uns vorbehalten, dem Kunden bleibt der Nachweis geringerer oder fehlender Kosten vorbehalten. K\u00f6nnen sich die Parteien im Falle einer Umbuchung nicht innerhalb von 1 Woche nach Eingang des Umbuchungswunsches bei uns auf einen anderen Termin einigen, so gilt die Umbuchung als Stornierung gem\u00e4\u00df vorstehender Klausel. Im \u00dcbrigen gelten die Regelungen gem\u00e4\u00df Ziffer 13.<\/span><\/li><\/ul><ul><li class=\"translation-block\">Buchungen von <strong>digitalen Seminaren<\/strong> und <strong>Blended-Learning-Seminaren<\/strong> k\u00f6nnen 14 Tage nach Vertragsschluss kostenlos storniert werden, sollte noch kein Login auf unsere E-Learning Plattform erfolgt sein. Mit dem ersten Login auf unserer E-Learning-Plattform \u201epersolog Academy\u201c ist keine Stornierung mehr m\u00f6glich. Das bedeutet mit dem Abschluss der Registrierung des Teilnehmenden bei uns und der zur Verf\u00fcgungstellung des Login-Zugangs. Ma\u00dfgeblich ist jeweils der Eingang der Stornierungserkl\u00e4rung des Kunden in Textform bei uns. Es steht dem Kunden frei, einen anderen Teilnehmenden zu benennen, um dadurch eine Stornierung abzuwenden. Dies ist nur m\u00f6glich, wenn der erste Login vom Kunden noch nicht erfolgt ist. Sollte f\u00fcr das Seminar eine vorherige Zertifizierung mit dem persolog\u00ae Pers\u00f6nlichkeits-Modell (oder eine andere Zertifizierung der persolog GmbH) erforderlich sein, so muss die Ersatzperson diese Voraussetzung erf\u00fcllen. Im \u00dcbrigen gilt Ziffer 13. zur Vertragsdauer und K\u00fcndigung.<\/li><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Der Kunde kann <\/span><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">digitale Seminare<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> und <\/span><strong style=\"font-style: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Blended-Learning-Seminare<\/strong><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\"> bis zu dem ersten Login (maximal 14 Tage nach Vertragsschluss) auf unserer E-Learning-Plattform \u201epersolog Academy\u201c\/Abschluss der Registrierung des Kunden bzw. Teilnehmers bei uns und die Zurverf\u00fcgungstellung des Login-Zugangs durch uns das gebuchte digitale Seminar kostenlos absagen (maximal 14 Tage nach Vertragsschluss) und auf ein digitales Seminar zu einem anderen Thema umbuchen. Sp\u00e4tere \u00c4nderungsw\u00fcnsche nehmen wir nicht an. Der Seminarpreis ist in diesem Fall unabh\u00e4ngig von der Teilnahme an dem gebuchten Seminar zu bezahlen. Nach Ablauf der Widerrufsfrist ist bei Umbuchungen von einem Seminar einer h\u00f6heren Preiskategorie in ein Seminar einer niedrigeren Preiskategorie der h\u00f6here Seminarpreis zu bezahlen. Ma\u00dfgeblich ist jeweils der Eingang der Erkl\u00e4rung des Kunden in Textform bei uns. Im \u00dcbrigen gelten die Regelungen gem. Ziffer 13.<\/span><\/li><\/ul><\/li><li><p>Stornierungs- oder Umbuchungsw\u00fcnsche des Kunden bed\u00fcrfen der Schriftform und sind zu richten an:<\/p><p>persolog GmbH<br \/>K\u00f6nigsbacher Stra\u00dfe 51<br \/>75196 Remchingen<br \/>Tel: +49 (0) 7232-3699-0<br \/>E-Mail: mail@persolog.com<\/p><p>Erst mit unserer Best\u00e4tigung des neuen Wunschtermins gelten Stornierungs- oder Umbuchungsw\u00fcnsche als erfolgt und fest gebucht.<\/p><\/li><li>F\u00fcr die Teilnahme an einem Seminar im Bereich Virtual Reality (nachfolgend \u201eVR-Seminare\u201c genannt) gelten erg\u00e4nzend die \u201eNutzungsbedingungen VR-Seminare\u201c.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb43975 e-flex e-con-boxed e-con e-parent\" data-id=\"fb43975\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-18c6301 e-flex e-con-boxed e-con e-child\" data-id=\"18c6301\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e049fc2 elementor-widget elementor-widget-heading\" data-id=\"e049fc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">V. Preise und Zahlungsbedingungen <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-644f473 elementor-widget elementor-widget-text-editor\" data-id=\"644f473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Es gelten die von uns zum Zeitpunkt des Vertragsschlusses angegebenen Preise.<\/li><\/ol><ol start=\"2\"><li>Unsere Preise verstehen sich in Euro zuz\u00fcglich der jeweils g\u00fcltigen gesetzlichen Mehrwertsteuer und zuz\u00fcglich Versandkosten. Die von uns angegebenen Bruttopreise gelten f\u00fcr Verbraucher. Bei der Lieferung von Waren werden die entsprechenden Versandkosten w\u00e4hrend des Bestellvorgangs angegeben und sind vom Kunden zu tragen. Ab einem Bestellwert von netto 500 Euro liefern wir innerhalb Deutschlands und \u00d6sterreichs versandkostenfrei. Die Wahl des Versandweges und der Versandart liegt in unserem Ermessen.<\/li><\/ol><ol start=\"3\"><li>Zahlungen erfolgen wie folgt:<\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li>Rechnung, zahlbar innerhalb von 10 Tagen nach Rechnungserhalt;<\/li><\/ul><\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Vorauskasse, <\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">zahlbar unmittelbar nach Rechnungserhalt;<\/span><\/li><\/ul><\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">\u00fcber den Dienstleister Mollie oder einen anderen von uns vor der Bestellung\/Buchung benannten Zahlungsdienstleister. Es gelten die dort angegebenen Zahlungsm\u00f6glichkeiten und Bedingungen.\u00a0<\/span><\/li><\/ul><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a67c424 elementor-widget elementor-widget-text-editor\" data-id=\"a67c424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol start=\"4\"><li>Zahlungen gelten erst mit der endg\u00fcltigen Gutschrift auf unserem Konto als erfolgt.<\/li><\/ol><ol start=\"5\"><li>Wir sind berechtigt, f\u00fcr s\u00e4mtliche Lieferungen und Leistungen Vorauskasse zu verlangen. Bei Vorauskasse erfolgt unsere Leistung erst nach erfolgter Gutschrift der Zahlung gem. Ziff.4.<\/li><\/ol><ol start=\"6\"><li>Im Falle des Zahlungsverzuges sind wir berechtigt, Verzugszinsen in gesetzlicher H\u00f6he zu verlangen. Die Geltendmachung weiterer Verzugssch\u00e4den bleibt hiervon unber\u00fchrt.<\/li><\/ol><ol start=\"7\"><li>Mit einer Forderung kann der Kunde uns gegen\u00fcber nur aufrechnen, wenn sie von uns unbestritten oder rechtskr\u00e4ftig festgestellt ist. Zur Aus\u00fcbung eines Zur\u00fcckbehaltungsrechts ist der Kunde nur insoweit befugt, als sein Gegenanspruch auf dem gleichen Vertragsverh\u00e4ltnis beruht. Ein Zur\u00fcckbehaltungsrecht wegen Teilleistungen gem\u00e4\u00df \u00a7 320 Abs. 2 BGB steht dem Kunden nicht zu.<\/li><\/ol><ol start=\"8\"><li>Bei K\u00e4ufen oder Buchungen \u00fcber die Digistore24 GmbH, gelten die dort hinterlegten allgemeine Gesch\u00e4ftsbedingungen des Digistore 24 f\u00fcr K\u00e4ufer.<\/li><li>Bei Buchung eines Inhouse-Seminars stellen wir im Rahmen einer Anzahlung 40 Tage vor dem Starttermin 50% der vereinbarten Verg\u00fctung in Rechnung. F\u00fcr Stornierungen des Kunden gilt die Regelung in Ziff. IV. 12.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7e695a e-flex e-con-boxed e-con e-parent\" data-id=\"c7e695a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b96f444 e-flex e-con-boxed e-con e-child\" data-id=\"b96f444\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df9d973 elementor-widget elementor-widget-heading\" data-id=\"df9d973\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">VI. Registrierung und Erstellung eines Kundenkontos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12d872e elementor-widget elementor-widget-text-editor\" data-id=\"12d872e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Eine Bestellung\/Buchung \u00fcber unseren Online-Shop ist nur nach Registrierung und erfolgreicher Erstellung eines Kundenkontos m\u00f6glich. Ein Anspruch auf Registrierung und Erstellung eines Kundenkontos besteht nicht.<\/li><li>F\u00fcr die Erstellung eines Kundenkontos gelten folgende Bedingungen:<br \/>a.\u00a0<span style=\"background-color: var(--ast-global-color-5); font-style: inherit; font-weight: inherit; color: var( --e-global-color-text );\">Ist der Kunde Verbraucher, k\u00f6nnen sich f\u00fcr nur einzelne vollj\u00e4hrige und voll gesch\u00e4ftsf\u00e4hige Personen (nicht hingegen Personengruppen wie z. B. Familien oder Ehepaare) registrieren; ist der Unternehmer, k\u00f6nnen sich nur voll gesch\u00e4ftsf\u00e4hige Personen und vertretungsberechtigte nat\u00fcrliche Personen f\u00fcr den Kunden registrieren. Bei Erl\u00f6schen der Vertretungsmacht der registrierten vertretungsberechtigten Person ist unverz\u00fcglich eine neue vertretungsberechtigte Person als Ansprechpartner zu benennen.<\/span><span style=\"font-style: inherit; font-weight: inherit;\"><span style=\"font-style: inherit; font-weight: inherit;\"><span style=\"color: rgba(0, 0, 0, 0);\">.<\/span><span style=\"color: #ba0000;\"><br \/><\/span><\/span><\/span>b. Ist der Kunde Verbraucher, hat er bei der Registrierung des Kundenkontos eine Anrede, seinen vollst\u00e4ndigen Namen nebst E-Mail-Adresse anzugeben und ein Passwort (Zugangsdaten) zu w\u00e4hlen. Ist der Kunde Unternehmer, hat er bei der Registrierung die vollst\u00e4ndige Firmen- oder Gesch\u00e4ftsbezeichnung oder der Name des Unternehmers nebst E-Mail-Adresse anzugeben und ein Passwort (Zugangsdaten) zu w\u00e4hlen. Der Kunde steht daf\u00fcr ein, dass die von ihm bei der Registrierung gemachten Angaben wahr und vollst\u00e4ndig sind. Macht ein Kunde unrichtige oder unvollst\u00e4ndige Angaben, sind wir berechtigt, das Konto des Kunden ohne Einhaltung einer Frist zu k\u00fcndigen und zu l\u00f6schen.<br \/>c. Der Kunde ist unter keinen Umst\u00e4nden berechtigt, seine Zugangsdaten und insbesondere sein Zugangspasswort an Dritte weiterzugeben. Sollten Dritte dennoch Zugang zu dem Kundenkonto erhalten oder der Kunde sonstige Anhaltspunkte f\u00fcr den Missbrauch seines Kontos haben, muss der Kunde uns dar\u00fcber umgehend informieren und seine Zugangsdaten \u00e4ndern. F\u00fcr den Fall eines Missbrauchs behalten wir uns die sofortige L\u00f6schung des Kontos sowie die Einleitung rechtlicher Schritte vor.<br \/>d. Mehrfachregistrierungen mit denselben E-Mail-Adressen eines Kunden sind nicht gestattet.<\/li><\/ol><ol start=\"3\"><li>Wir k\u00f6nnen ein Kundenkonto jederzeit sperren oder l\u00f6schen, wenn es missbr\u00e4uchlich genutzt wird oder \u00fcber das Kundenkonto rechtswidrige, wettbewerbswidrige, strafrechtlich relevante oder sittenwidrige Handlungen begangen werden.<\/li><li>Zertifizierte persolog-Trainer erhalten nach Abschluss der Zertifizierung die M\u00f6glichkeit, im Webshop Print- und Online-Produkte des jeweiligen Modells zu Trainerkonditionen einzukaufen. Hierzu ist die Registrierung im Shop erforderlich.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b1a7d3 e-flex e-con-boxed e-con e-parent\" data-id=\"6b1a7d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-36ab9f7 e-flex e-con-boxed e-con e-child\" data-id=\"36ab9f7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c995283 elementor-widget elementor-widget-heading\" data-id=\"c995283\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">VII. Urheber- und Eigentumsrechte, Nutzungsrechte<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd44ac0 elementor-widget elementor-widget-text-editor\" data-id=\"fd44ac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Die von uns bereitgestellten Produkte\/Waren und Inhalte\/digitalen Inhalte unterliegen dem Schutz des Urheberrechts oder anderer Rechte von uns oder Dritten und d\u00fcrfen nur im Rahmen des vertraglich vereinbarten Nutzungszwecks genutzt werden. F\u00fcr die Nutzung dieser Produkte\/Waren und Inhalte\/digitalen Inhalte erwirbt der Kunde unter der Voraussetzung der Zahlung des geschuldeten und f\u00e4lligen Kauf-\/Seminarpreises f\u00fcr sich und im Umfang seiner Bestellung\/Buchung und der einzelvertraglichen Vereinbarung an den jeweiligen Produkten und Inhalten ein einfaches, nicht ausschlie\u00dfliches, nicht unterlizenzierbares und nicht auf Dritte \u00fcbertragbares Recht zur Nutzung der jeweiligen Produkte und Inhalte f\u00fcr eigene Zwecke, ggf. auch f\u00fcr andere vorgesehene Nutzungsberechtigte. Das Nutzungsrecht berechtigt den Kunden zum lesenden Zugriff auf die Inhalte des Produkts sowie zum Herunterladen, einmaligen Speichern und einmaligen Drucken von Inhalten.<\/li><\/ol><ol start=\"2\"><li>Eine dar\u00fcber hinausgehende Nutzung ist ausgeschlossen und bedarf der vorherigen gesonderten schriftlichen Zustimmung des jeweiligen Rechteinhabers, sofern eine solche Nutzung nicht durch zwingende gesetzliche Vorschriften zul\u00e4ssig ist. Insbesondere ist es dem Kunden oder anderen berechtigten Nutzern untersagt, die bereitgestellten Produkte und Inhalte \u2013 auch auszugsweise \u2013 zu kopieren, Urheberrechtsvermerke oder Markenkennzeichnungen zu entfernen, die Produkte und Inhalte zu modifizieren oder zu ver\u00e4ndern, die Produkte und Inhalte auf andere Datentr\u00e4ger oder Netzwerke zu kopieren, die Erstellung und Nutzung von Vervielf\u00e4ltigungen sowie jede entgeltliche oder unentgeltliche Weitergabe, jede Zug\u00e4nglichmachung oder jede Form der gewerblichen Nutzung. Der Kunde darf keine Mittel zur \u00dcberwindung oder Umgehung dieser Ma\u00dfnahmen einsetzen.<\/li><li>Dem Kunden ist es untersagt, urheberrechtlich gesch\u00fctzte Texte und Inhalte aus persolog-Produkten sowie vertrauliche oder pers\u00f6nliche Informationen und Inhalte im Zusammenhang mit persolog-Produkten in KI-Systeme (z. B. Chatbots, generative KI, Text- oder Bildgeneratoren) einzugeben und\/oder hochzuladen und\/oder anderweitig in KI-Systemen zu verarbeiten. Dies gilt insbesondere f\u00fcr Frageb\u00f6gen, Profilinhalte, Auswertungen oder Kernaussagen aus dem Arbeitsbuch.<\/li><li>Beim Erwerb von eBooks gelten erg\u00e4nzend die jeweilige Produktbeschreibung und die nachfolgenden Regelungen:<\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Wir stellen dem Kunden das E-Book nach Vertragsschluss zum Download zur Verf\u00fcgung.<\/span><\/li><\/ul><\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Mit dem Download des E-Books erwirbt der Kunde ein einfaches, nicht ausschlie\u00dfliches, nicht unterlizenzierbares, nicht auf Dritte \u00fcbertragbares und zeitlich unbefristetes Nutzungsrecht an dem E-Book. Ein Erwerb von Rechten an den Inhalten oder dem eBook selbst ist damit nicht verbunden.<\/span><\/li><\/ul><\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Der Kunde ist berechtigt, das eBook maximal dreimal herunterzuladen und auf bis zu drei Endger\u00e4ten zu speichern. Der Kunde kann das eBook beliebig oft auf den Endger\u00e4ten abrufen.<\/span><\/li><\/ul><\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Die Weitergabe des E-Books, Kopien des E-Books oder Inhalte des E-Books an Dritte ist nicht gestattet. Ebenso ist der Kunde nicht berechtigt, das E-Book, Kopien oder Inhalte des E-Books \u00f6ffentlich zug\u00e4nglich zu machen, im Internet oder in Netzwerken einzustellen oder weiterzuverkaufen.<\/span><\/li><\/ul><\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); background-color: var(--ast-global-color-5);\">Der Kunde ist nicht berechtigt, den Inhalt eines eBooks inhaltlich oder redaktionell zu ver\u00e4ndern. Der Kunde darf Marken, Urheberrechtsvermerke, digitale Wasserzeichen nicht entfernen oder ver\u00e4ndern. Dem Kunden ist es nicht gestattet, Schutzma\u00dfnahmen gegen Urheberrechtsverletzungen zu entfernen oder zu umgehen.<\/span><\/li><\/ul><\/li><\/ol><ol><li style=\"list-style-type: none;\"><ul><li>Wir sind berechtigt, die M\u00f6glichkeit des erneuten Downloads des E-Books gem\u00e4\u00df Abschnitt VII.4.c dieser AGB zu sperren, sofern uns bekannt wird, dass der Kunde gegen die vorstehenden AGB verst\u00f6\u00dft.<\/li><\/ul><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37a2089 e-flex e-con-boxed e-con e-parent\" data-id=\"37a2089\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-12f2034 e-flex e-con-boxed e-con e-child\" data-id=\"12f2034\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f17a6ec elementor-widget elementor-widget-heading\" data-id=\"f17a6ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">VIII. Gew\u00e4hrleistung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e137f80 elementor-widget elementor-widget-text-editor\" data-id=\"e137f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><ol><li>Wir stehen im Zusammenhang mit Waren und digitalen Produkten f\u00fcr M\u00e4ngel im Rahmen der gesetzlichen Bestimmungen ein.<\/li><li>Ist der Kunde Unternehmer gilt zus\u00e4tzlich: Rechts- oder Sachm\u00e4ngel, das Fehlen einer von uns garantierten Beschaffenheit einer von uns gelieferten Sache (nachfolgend: M\u00e4ngel) sowie die Zuviel-, Zuwenig- oder Falschlieferung (nachfolgend: Abweichungen) sind unverz\u00fcglich, sp\u00e4testens innerhalb von 5 Werktagen nach Empfang der Liefersache schriftlich geltend zu machen, sofern es sich um Abweichungen oder \u00e4u\u00dferlich erkennbare M\u00e4ngel handelt. Nicht offensichtliche M\u00e4ngel sind vom Vertragspartner ebenfalls unverz\u00fcglich, sp\u00e4testens innerhalb von 5 Werktagen nach Entdeckung schriftlich geltend zu machen. Werden Abweichungen oder M\u00e4ngel nicht innerhalb der genannten Fristen geltend gemacht, sind jegliche Gew\u00e4hrleistungsanspr\u00fcche des Kunden gegen uns ausgeschlossen.<\/li><li>Bei Vertr\u00e4gen mit Verbrauchern \u00fcber die Lieferung von Waren betr\u00e4gt die Gew\u00e4hrleistungsfrist 2 Jahre ab Ablieferung der Ware.<\/li><li>F\u00fcr Unternehmer ist die Gew\u00e4hrleistungsfrist auf ein Jahr ab Gefahr\u00fcbergang beschr\u00e4nkt, es sei denn, es sind gesetzlich zwingend l\u00e4ngere Verj\u00e4hrungsfristen vorgesehen.<\/li><li>Im Zusammenhang mit der Haftung f\u00fcr M\u00e4ngel von Software ist zu ber\u00fccksichtigen, dass eine fehlerfreie Funktionsweise der Software unter s\u00e4mtlichen Anwendungsbedingungen nicht realisiert werden kann. Die M\u00e4ngelhaftung ist daher ausgeschlossen, wenn die Software auf einem System betrieben wird, welches nicht den auf der Verpackung oder in der Dokumentation angegebenen Mindestvoraussetzungen entspricht, es sei denn, der Kunde weist nach, dass der Fehler auch vorliegen w\u00fcrde, wenn die Software auf einem System eingesetzt worden w\u00e4re, welches diesen Mindestvoraussetzungen gen\u00fcgt.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf21c1d e-flex e-con-boxed e-con e-parent\" data-id=\"cf21c1d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-974646a e-flex e-con-boxed e-con e-child\" data-id=\"974646a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3e204 elementor-widget elementor-widget-heading\" data-id=\"7a3e204\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">IX. Haftung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b756d8b elementor-widget elementor-widget-text-editor\" data-id=\"b756d8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><ol><li>Wir haften nach den gesetzlichen Bestimmungen, sofern der Kunde Schadens- oder Aufwendungsersatzanspr\u00fcche geltend macht, die auf Vorsatz oder grober Fahrl\u00e4ssigkeit, einschlie\u00dflich Vorsatz oder grober Fahrl\u00e4ssigkeit unserer Vertreter oder Erf\u00fcllungsgehilfen beruhen. Soweit uns keine vors\u00e4tzliche Vertragsverletzung angelastet wird, ist die Schadensersatzhaftung auf den vorhersehbaren, typischerweise eintretenden Schaden begrenzt.<\/li><li>Wir haften nach den gesetzlichen Bestimmungen, sofern wir schuldhaft eine wesentliche Vertragspflicht verletzen; in diesem Fall ist aber die Schadensersatzhaftung auf den bei Vertragsschluss vorhersehbaren, typischerweise eintretenden Schaden begrenzt. Wir haften nicht f\u00fcr entgangenen Gewinn.<\/li><li>Die Haftung wegen schuldhafter Verletzung des Lebens, des K\u00f6rpers oder der Gesundheit bleibt unber\u00fchrt; dies gilt auch f\u00fcr die zwingende Haftung nach dem Produkthaftungsgesetz.<\/li><li>Soweit vorstehend oder in unseren Nutzungsbedingungen nichts Abweichendes geregelt ist, ist eine Haftung \u2013 unabh\u00e4ngig von der Rechtsnatur des geltend gemachten Anspruchs \u2013 ausgeschlossen. Dies gilt insbesondere f\u00fcr Schadensersatzanspr\u00fcche aus Verschulden bei Vertragsschluss, aus sonstigen Pflichtverletzungen oder aus deliktischen Anspr\u00fcchen auf Ersatz von Sachsch\u00e4den gem\u00e4\u00df \u00a7 823 BGB.<\/li><li>Die pers\u00f6nliche Haftung unserer gesetzlichen Vertreter, Erf\u00fcllungsgehilfen und Mitarbeiter f\u00fcr von ihnen leicht fahrl\u00e4ssig verursachte Sch\u00e4den ist ausgeschlossen. Soweit die Schadensersatzhaftung uns gegen\u00fcber ausgeschlossen oder eingeschr\u00e4nkt ist, gilt dies auch im Hinblick auf die pers\u00f6nliche Schadensersatzhaftung der vorgenannten Personen.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db4e86d e-flex e-con-boxed e-con e-parent\" data-id=\"db4e86d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-55d354b e-flex e-con-boxed e-con e-child\" data-id=\"55d354b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b26339 elementor-widget elementor-widget-heading\" data-id=\"4b26339\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">X. Eigentumsvorbehalt<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05410e3 elementor-widget elementor-widget-text-editor\" data-id=\"05410e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><ol><li>Die Einr\u00e4umung der Nutzungsrechte an digitalen Inhalten erfolgt unter der aufschiebenden Bedingung der vollst\u00e4ndigen Bezahlung des diesbez\u00fcglichen Preises.<\/li><li>Ist der Kunde Verbraucher, bleiben gelieferte Waren bleiben bis zur vollst\u00e4ndigen Bezahlung des diesbez\u00fcglichen Preises einschlie\u00dflich der gegebenenfalls anfallenden Fracht- Liefer- und Versandkosten oder sonstigen Kosten in unserem Eigentum.<\/li><li>Ist der Kunde Unternehmer, gelten folgende Bestimmungen:<br \/>a. Im Falle der Lieferung von Waren bleibt die Ware bis zur vollst\u00e4ndigen Bezahlung s\u00e4mtlicher Forderungen aus der Gesch\u00e4ftsverbindung zwischen uns und dem Kunden in unserem Eigentum.<br \/>b. Soweit das jeweilige Recht, in dessen Bereich sich die Ware befindet, einen Eigentumsvorbehalt nicht zul\u00e4sst, sind wir berechtigt, alle Rechte auszu\u00fcben, die wir uns an der Ware anderweitig vorbehalten k\u00f6nnen. Der Kunde ist verpflichtet, bei s\u00e4mtlichen Ma\u00dfnahmen mitzuwirken, die wir zum Schutz unseres Eigentumsrechts oder an dessen Stelle eines anderen Sicherungsrechtes an der Ware treffen wollen.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2390eb9 e-flex e-con-boxed e-con e-parent\" data-id=\"2390eb9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ea67f17 e-flex e-con-boxed e-con e-child\" data-id=\"ea67f17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-184bdb9 e-con-full e-flex e-con e-child\" data-id=\"184bdb9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33fe913 elementor-widget elementor-widget-heading\" data-id=\"33fe913\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">XI. Online-Streitbeilegung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92b9bb6 e-con-full e-flex e-con e-child\" data-id=\"92b9bb6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4daf32e elementor-widget elementor-widget-text-editor\" data-id=\"4daf32e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Online-Streitbeilegung gem\u00e4\u00df Art. 14 Abs. 1 ODR-Verordnung:\u00a0<\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS-Plattform) bereit. Diese finden Sie folgendem Link: https:\/\/webgate.ec.europa.eu\/odr.<\/span><\/li><li><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Wir sind\u00a0<\/span>zur Teilnahme an einem Streitbeteiligungsverfahren weder verpflichtet, noch bereit.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bc3274 elementor-widget elementor-widget-heading\" data-id=\"3bc3274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">XII. Datenschutz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-522d090 elementor-widget elementor-widget-text-editor\" data-id=\"522d090\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Die hierf\u00fcr erforderlichen Kunden- und Lieferdaten werden von uns entsprechend den Bestimmungen des deutschen Datenschutzrechts erhoben, verarbeitet und gespeichert. Die Daten werden zur Vertragserf\u00fcllung genutzt und in diesem Zusammenhang gegebenenfalls auch an Dritte weitergegeben.<\/li><li>Der \u00fcber die Vertragserf\u00fcllung hinausgehenden Datenverwendung kann der Kunde jederzeit in Textform gegen\u00fcber uns, z. B. per E-Mail an datenschutz@persolog.com, widersprechen<p>3. Im \u00dcbrigen gilt unsere Datenschutzerkl\u00e4rung unter <strong>https:\/\/www.persolog.de\/allgemeine-geschaeftsbedingungen\/datenschutz\/.<\/strong><\/p><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ca1cdc e-flex e-con-boxed e-con e-parent\" data-id=\"0ca1cdc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b939c3b e-flex e-con-boxed e-con e-child\" data-id=\"b939c3b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-598b8d1 elementor-widget elementor-widget-heading\" data-id=\"598b8d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">XII. Erf\u00fcllungsort, Gerichtsstand und anzuwendendes Recht<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f58d2c2 elementor-widget elementor-widget-text-editor\" data-id=\"f58d2c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><ol><li>Erf\u00fcllungsort und Gerichtsstand f\u00fcr alle sich aus dem Vertragsverh\u00e4ltnis mittelbar oder unmittelbar ergebenden Verpflichtungen ist der Sitz unseres Gesch\u00e4ftssitzes in 75196 Remchingen. Wir sind auch berechtigt, am Sitz des Kunden zu klagen.<\/li><\/ol><ol start=\"2\"><li>Es gilt das Recht der Bundesrepublik Deutschland unter Ausschluss der Bestimmungen des Internationalen Privatrechts und des \u00dcbereinkommens der Vereinten Nationen \u00fcber Vertr\u00e4ge \u00fcber den internationalen Warenkauf (CISG).<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a948ce7 e-con-full e-flex e-con e-child\" data-id=\"a948ce7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98b002b elementor-widget elementor-widget-heading\" data-id=\"98b002b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">XIV. Widerrufsrecht f\u00fcr Verbraucher bei Fernabsatzvertr\u00e4gen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46695b1 elementor-widget elementor-widget-text-editor\" data-id=\"46695b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>\u00a0Ist der Kunde Verbraucher im Sinne von Ziffer I.3. dieser Gesch\u00e4ftsbedingungen und kommt ein Vertrag \u00fcber die Bestellung von Waren oder Buchung von offenen Gruppenseminaren (als Pr\u00e4senzseminare oder Online-Seminare), digitalen Seminaren oder Blended-Learning-Seminaren ausschlie\u00dflich unter Verwendung von Fernkommunikationsmitteln zustande (sog. Fernabsatzgesch\u00e4ft gem. \u00a7 312 c BGB), steht ihm grunds\u00e4tzlich ein gesetzliches Widerrufsrecht zu. Die Bestimmungen zum vorzeitigen Erl\u00f6schen des Widerrufsrechts sind in Absatz 2 und 3 dieser Ziffer geregelt. In Absatz 4 dieser Ziffer findet sich ein Muster-Widerrufsformular.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e3c471 e-flex e-con-boxed e-con e-parent\" data-id=\"6e3c471\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4f365f7 e-flex e-con-boxed e-con e-child\" data-id=\"4f365f7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-57ca41a e-con-full e-flex e-con e-child\" data-id=\"57ca41a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e815a39 elementor-widget elementor-widget-text-editor\" data-id=\"e815a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Widerrufsbelehrung<\/p>\n<p>Widerrufsrecht<\/p>\n<p>Sie haben das Recht,&nbsp;<span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen.<br><\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag,<br>a.&nbsp;<\/span><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">des Vertragsschlusses im Falle eines Dienstleistungsvertrages (offene Gruppenseminare als Pr\u00e4senzseminare oder Online-Seminare) oder eines Vertrages \u00fcber die Lieferung nicht auf einem k\u00f6rperlichen Datentr\u00e4ger befindlichen digitalen Inhalten (digitale Seminare, Blended-Learning-Seminare oder Bestellungen von eBooks);<br>b.&nbsp;<\/span><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">an dem Sie oder ein von Ihnen benannter Dritter, der nicht Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat im Falle der Bestellung von einer Ware\/mehreren Waren im Rahmen einer einheitlichen Bestellung, wenn diese einheitlich geliefert werden;<br>an dem Sie oder ein von Ihnen benannter Dritter, der nicht Bef\u00f6rderer ist, die letzte Ware in Besitz genommen haben bzw. hat im Falle der Bestellung von mehreren Waren im Rahmen einer einheitlichen Bestellung, wenn diese getrennt geliefert werden;<br>d. an dem&nbsp;<\/span><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Sie oder ein von Ihnen benannter Dritter, der nicht Bef\u00f6rderer ist, die letzte Teilsendung oder das letzte St\u00fcck in Besitz genommen haben bzw. hat im Falle der Bestellung einer Ware, die in mehreren Teilsendungen oder St\u00fccken geliefert wird;<br>e. an dem&nbsp;<\/span><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Sie oder ein von Ihnen benannter Dritter, der nicht Bef\u00f6rderer ist, die erste Ware in Besitz genommen haben bzw. hat im Falle der Bestellung von Waren zur regelm\u00e4\u00dfigen Lieferung von Waren \u00fcber einen festgelegten Zeitraum hinweg.<\/span><\/p>\n<p><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Um&nbsp;<\/span><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (persolog GmbH, K\u00f6nigsbacher Stra\u00dfe 51, 75196 Remchingen, Tel: +49 (0) 7232-3699-0, E-Mail: mail@persolog.com) mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist.<\/span><\/p>\n<p><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Zur Wahrung&nbsp;<\/span><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/span><\/p>\n<p><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Folgen des Widerrufs<br>Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstige Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrages bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<\/span><\/p>\n<p>Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.<\/p><p>Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrages unterrichten, an uns (persolog GmbH, K\u00f6nigsbacher Stra\u00dfe 51, 75196 Remchingen) zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<\/p><p>Sie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren. Sie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.\nHaben Sie im Zusammenhang mit offenen Gruppenseminaren (Pr\u00e4senzseminare oder Online-Seminare) verlangt, dass die Dienstleistungen w\u00e4hrend der Widerrufsfrist beginnen soll, so haben Sie uns einen angemessenen Betrag zu zahlen, der dem Anteil der bis zu dem Zeitpunkt, zu dem Sie uns von der Aus\u00fcbung des Widerrufsrechts hinsichtlich dieses Vertrags unterrichten, bereits erbrachten Dienstleistungen im Vergleich zum Gesamtumfang der im Vertrag vorgesehenen Dienstleistungen entspricht.<\/p><p><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\"><\/span><\/p><p>Ende der Widerrufsbelehrung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d116948 elementor-widget elementor-widget-text-editor\" data-id=\"d116948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2.\u00a0<span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Das Widerrufsrecht erlischt bei der Buchung offener Gruppenseminaren (Pr\u00e4senzseminare oder Online-Seminare) gem. \u00a7 356 Abs. 4 BGB vorzeitig mit der vollst\u00e4ndigen Erbringung der Dienstleistung durch uns, wenn der Verbraucher vor Beginn der Erbringung ausdr\u00fccklich zugestimmt hat, dass wir mit der Erbringung der Dienstleistung vor Ablauf der Widerrufsfrist beginnen und der Verbraucher seine Kenntnis davon best\u00e4tigt hat, dass er durch seine Zustimmung mit vollst\u00e4ndiger Vertragserf\u00fcllung sein Widerrufsrecht erlischt. Dies wird durch eine entsprechende Opt-In-Box bei der Buchung sichergestellt.<\/span><\/p><p><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">3. Bei der\u00a0<\/span><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Bereitstellung von nicht auf einem k\u00f6rperlichen Datentr\u00e4ger befindlichen digitalen Inhalten (digitale Seminare, Blended-Learning-Seminare oder Bestellungen von eBook) erlischt nach \u00a7 356 Abs. 5 BGB das Widerrufsrecht vorzeitig, wenn der Verbraucher ausdr\u00fccklich zugestimmt hat, dass wir mit der Vertragserf\u00fcllung vor Ablauf der Widerrufsfrist beginnen und der Verbraucher seine Kenntnis da\u00dfvon best\u00e4tigt hat, dass er durch seine Zustimmung mit Beginn der Vertragserf\u00fcllung sein Widerrufsrecht erlischt. Dies wird durch eine entsprechende Opt-In-Box bei der Bestellung bzw. Buchung sichergestellt. Wir stellen dem Verbraucher eine Best\u00e4tigung hier r\u00fcber nach Vertragsschluss zur Verf\u00fcgung.<\/span><\/p><p><span style=\"text-align: var(--text-align); background-color: var(--ast-global-color-5);\">\u00dcber das Muster-Widerrufsformular informieren wir Sie nach den gesetzlichen Vorgaben wie folgt:\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2178d69 elementor-widget elementor-widget-text-editor\" data-id=\"2178d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Muster-Widerrufsformular<\/p>\n<p>(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<\/p>\n<p>- An (persolog GmbH, K\u00f6nigsbacher Stra\u00dfe 51, 75196 Remchingen, E-Mail: mail@persolog.com):<\/p><p>-<span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5); white-space: pre;\">\t<\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)\/ die Erbringung der folgenden Dienstleistung (*)<\/span><\/p><p>-<span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5); white-space: pre;\">\t<\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Bestellt am (*)\/erhalten am (*)<\/span><\/p><p>-<span style=\"white-space:pre\">\t<\/span>Name des\/der Verbraucher(s)<\/p><p>-<span style=\"white-space:pre\">\t<\/span>Anschrift des\/der Verbraucher(s)<\/p><p>-<span style=\"white-space:pre\">\t<\/span>Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<\/p><p>-<span style=\"white-space:pre\">\t<\/span>Datum<\/p><p>-<span style=\"white-space:pre\">\t<\/span>(*) Unzutreffendes streichen<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f16e41 elementor-widget elementor-widget-heading\" data-id=\"4f16e41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">XV. Widerrufsrecht des Teilnehmers bei der Buchung von Blended-Learning-Seminaren<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d3fd8 elementor-widget elementor-widget-text-editor\" data-id=\"48d3fd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1. Ist der Kunde Teilnehmer eines Blended-Learning-Seminars, steht ihm grunds\u00e4tzlich ein gesetzliches Widerrufsrecht zu. Die Bestimmungen zum vorzeitigen Erl\u00f6schen des Widerrufsrechts sind in Absatz 2 dieser Ziffer geregelt. In Absatz 3 dieser Ziffer findet sich ein Muster-Widerrufsformular.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-652cb73 elementor-widget elementor-widget-text-editor\" data-id=\"652cb73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Widerrufsbelehrung<\/p>\n<p>Widerrufsrecht<br><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen.<\/span><\/p>\n<p>Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag des Vertragsschlusses.<\/p>\n<p>Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (persolog GmbH, K\u00f6nigsbacher Stra\u00dfe 51, 75196 Remchingen, Tel: +49 (0) 7232-3699-0, E-Mail: mail@persolog.com) mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist.&nbsp;<\/p>\n<p>Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p>Folgen des Widerrufs<br><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstige Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrages bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<\/span><\/p>\n<p>Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir das Unterrichtsmaterial wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie das Unterrichtsmaterial zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.<\/p>\n<p>Sie haben das Unterrichtsmaterial unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrages unterrichten, an uns (persolog GmbH, K\u00f6nigsbacher Stra\u00dfe 51, 75196 Remchingen) zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<\/p>\n<p>Sie tragen die unmittelbaren Kosten der R\u00fccksendung des Unterrichtsmaterials.&nbsp;<\/p>\n<p>Sie m\u00fcssen f\u00fcr einen etwaigen Wertverlust des Unterrichtsmaterials nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise des Unterrichtsmaterials nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p>Ende der Widerrufsbelehrung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2b642c elementor-widget elementor-widget-text-editor\" data-id=\"b2b642c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2. Bei der Bereitstellung von nicht auf einem k\u00f6rperlichen Datentr\u00e4ger befindlichen digitalen Inhalten erlischt nach \u00a7 356 Abs. 5 BGB das Widerrufsrecht vorzeitig, wenn der Teilnehmer ausdr\u00fccklich zugestimmt hat, dass wir mit der Vertragserf\u00fcllung vor Ablauf der Widerrufsfrist beginnen und der Teilnehmer seine Kenntnis davon best\u00e4tigt hat, dass er durch seine Zustimmung mit Beginn der Vertragserf\u00fcllung sein Widerrufsrecht erlischt. Dies wird durch eine entsprechende Opt-In-Box bei der Bestellung bzw. Buchung sichergestellt. Wir stellen dem Teilnehmer eine Best\u00e4tigung hier\u00fcber nach Vertragsschluss zur Verf\u00fcgung.<\/p><p>3. \u00dcber das Muster-Widerrufsformular informieren wir sie nach den gesetzlichen Vorgaben wie folgt:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63d50c8 elementor-widget elementor-widget-text-editor\" data-id=\"63d50c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Muster-Widerrufsformular<\/p><p>(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<\/p><p>\u00a0<\/p><p>\u2014 An (persolog GmbH, K\u00f6nigsbacher Stra\u00dfe 51, 75196 Remchingen, E-Mail: mail@persolog.com):<\/p><p><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">- Ich\/wir (*) k\u00fcndige(n) hiermit den von mir\/uns (*) abgeschlossenen Vertrag f\u00fcr den Kauf der folgenden Produkte (*)\/die Provision der folgenden Dienstleistung (*)<\/span><\/p><p><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var(--ast-global-color-5);\">- Bestellt am (*)\/erhalten am (*)<\/span><\/p><p>- Name des\/der Verbraucher(s)<\/p><p>- Anschrift des\/der Verbraucher(s)<\/p><p>- Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<\/p><p>Datum<\/p><p>- (*) Unzutreffendes streichen<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-001be45 elementor-widget elementor-widget-text-editor\" data-id=\"001be45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stand: September 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14923d2 elementor-widget elementor-widget-text-editor\" data-id=\"14923d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Zufriedenheits-Garantie f\u00fcr persolog Zertifizierungen<\/strong><\/h2><ol><li><h5><strong> Geltungsbereich<\/strong><\/h5><\/li><\/ol><p>Diese Zufriedenheits-Garantie gilt ausschlie\u00dflich f\u00fcr Live-Online-Zertifizierungen sowie Pr\u00e4senz-Zertifizierungen (Gruppenseminare), die bis sp\u00e4testens 31. Dezember 2025 gebucht werden. Nicht umfasst sind digitale und blendend Zertifizierungen (asynchrone Online-Kurse) sowie alle weiteren Seminare.<\/p><ol start=\"2\"><li><h5><strong> Leistungsumfang der Garantie<\/strong><\/h5><\/li><\/ol><p>Wenn Sie w\u00e4hrend Ihrer Zertifizierung \u2013 live-online oder in Pr\u00e4senz \u2013 das Gef\u00fchl haben, nichts Neues gelernt zu haben, erhalten Sie den vollen Teilnahmebetrag zur\u00fcckerstattet. Die Erstattung erfolgt ohne Diskussion und ohne Kleingedrucktes.<\/p><ol start=\"3\"><li><h5><strong> Einschr\u00e4nkungen und Folgen des R\u00fccktritts<\/strong><\/h5><\/li><\/ol><p>Mit der Inanspruchnahme der Zufriedenheits-Garantie gelten folgende Bedingungen:<\/p><ul><li>Sie verlieren das Recht auf die F\u00fchrung des Titels \u201ezertifizierter persolog Trainer\u201c zur jeweiligen Zertifizierung.<\/li><li>Ihr Zugang zur persolog Online Academy bzw. zur jeweiligen Zertifizierung wird beendet.<\/li><li>Sie erhalten keine Trainerpreise und keinen persolog Support mehr.<\/li><li>Sie sind verpflichtet, den erhaltenen Trainerkoffer auf eigene Kosten unber\u00fchrt und unbesch\u00e4digt zur\u00fcckzusenden.<\/li><\/ul><ol start=\"4\"><li><h5><strong> Verfahren zur Inanspruchnahme<\/strong><\/h5><\/li><\/ol><p>Um Ihre Zufriedenheits-Garantie in Anspruch zu nehmen, schicken Sie uns bitte Ihren Trainerkoffer zur\u00fcck und melden Sie sich telefonisch bei uns unter:<\/p><p>\ud83d\udcde +49 7232 3699-0<\/p><p>Wir w\u00fcrden uns freuen, wenn Sie uns dabei ein kurzes Feedback geben, warum Sie zur\u00fccktreten m\u00f6chten \u2013 damit wir unsere Zertifizierungen kontinuierlich verbessern k\u00f6nnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8862d4b elementor-widget elementor-widget-heading\" data-id=\"8862d4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nutzungsbedingungen f\u00fcr digitale Mitgliedschaften der persolog GmbH<br>\nWir freuen uns, dass Sie sich f\u00fcr eine oder mehrere Mitgliedschaften bei der persolog GmbH entschieden haben.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b106526 elementor-widget elementor-widget-heading\" data-id=\"b106526\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\nDie folgenden Nutzungsbedingungen gelten f\u00fcr die persolog GmbH, K\u00f6nigsbacher Stra\u00dfe 51, 75196 Remchingen, Deutschland, Umsatzsteuer-Identifikationsnummer: DE231004454. <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4fee71 e-flex e-con-boxed e-con e-child\" data-id=\"b4fee71\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e2512f elementor-widget elementor-widget-heading\" data-id=\"0e2512f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">I. Geltungsbereich<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf1120f elementor-widget elementor-widget-text-editor\" data-id=\"bf1120f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>F\u00fcr alle Angebote, Lieferungen und sonstigen Leistungen im Zusammenhang mit digitalen Mitgliedschaften in der \u201epersolog Academy\u201c gelten die nachstehenden Bedingungen in ihrer jeweils aktuellen Fassung. Unsere Allgemeinen Nutzungsbedingungen (nachfolgend \u201eNutzungsbedingungen\u201c genannt) gelten auch f\u00fcr alle k\u00fcnftigen Gesch\u00e4fte.<\/li><li>Es gelten ausschlie\u00dflich unsere Nutzungsbedingungen. Entgegenstehende, abweichende oder erg\u00e4nzende Bedingungen des Vertragspartners\/Nutzers (nachfolgend \u201eKunde\u201c genannt) erkennen wir nicht an, es sei denn, wir h\u00e4tten ausdr\u00fccklich schriftlich ihrer Geltung zugestimmt. Unsere Nutzungsbedingungen gelten auch dann, wenn wir in Kenntnis entgegenstehender oder abweichender Bedingungen des Kunden unsere Leistungen vorbehaltlos erbringen.<\/li><li>Unsere Verkaufsbedingungen gelten nur gegen\u00fcber Unternehmern im Sinne des \u00a7 310 I BGB sowie gegen\u00fcber juristischen Personen des \u00f6ffentlichen Rechts und \u00f6ffentlich-rechtlichen Sonderverm\u00f6gen.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0090018 e-flex e-con-boxed e-con e-child\" data-id=\"0090018\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-944de7a e-flex e-con-boxed e-con e-child\" data-id=\"944de7a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e38bbb9 elementor-widget elementor-widget-heading\" data-id=\"e38bbb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">II. Vertragsschluss<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea3db47 elementor-widget elementor-widget-text-editor\" data-id=\"ea3db47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Die Inhalte auf unserer Homepage und in deren sonstigen Ver\u00f6ffentlichungen zu Pr\u00e4sentations- und\/oder Werbezwecken stellen kein bindendes Angebot, sondern lediglich eine Aufforderung an den Kunden dar, ein verbindliches Angebot abzugeben. Der Kunde gibt ein verbindliches Angebot zur Bestellung der im Warenkorb enthaltenen digitalen Angebote ab, indem er nach Durchlaufen des Online-Bestellvorgangs die Bestellung durch Bet\u00e4tigung des Buttons \u201eJetzt kaufen\u201c absendet. Das Angebot kann nur abgegeben werden, wenn der Kunde diese Nutzungsbedingungen durch Anklicken des Buttons \u201eAllgemeine Nutzungsbedingungen akzeptieren\u201c akzeptiert und dadurch in sein Angebot aufgenommen hat.<br \/><br \/><\/li><li>Anschlie\u00dfend senden wir dem Kunden eine Bestellbest\u00e4tigung per E-Mail. Die Bestellbest\u00e4tigung stellt die Annahme des Angebots dar. Der Inhalt des Vertrages ergibt sich daraus.<br \/><br \/><\/li><li>Die Pflichten nach \u00a7 312i Abs. 1 Satz 1 Nr. 1 bis Nr. 3 und Satz 2 BGB finden keine Anwendung.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb9ebaa e-flex e-con-boxed e-con e-parent\" data-id=\"bb9ebaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a67974 e-flex e-con-boxed e-con e-child\" data-id=\"9a67974\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd2a034 elementor-widget elementor-widget-heading\" data-id=\"bd2a034\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">III. Zugangsvoraussetzungen, Leistungsbeschreibung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6dd0fc elementor-widget elementor-widget-text-editor\" data-id=\"c6dd0fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>F\u00fcr die Bestellung und Nutzung digitaler Mitgliedschaften ben\u00f6tigt der Kunde eine g\u00fcltige E-Mail-Adresse und eine leistungsstarke Internetverbindung.<br \/><br \/><\/li><li>Verbindungsgeb\u00fchren f\u00fcr das Internet sowie etwaige weitere Kosten, die durch den Abschluss eines Mobilfunkvertrages entstehen, sind vom Kunden zu tragen und sind nicht Bestandteil der digitalen Mitgliedschaften.<br \/>Die digitalen Inhalte der \u201epersolog Academy\u201c k\u00f6nnen von Kunden \u00fcber die Website der \u201epersolog Academy\u201c unter onlineacademy.persolog.com digital abgerufen und genutzt werden.<br \/><br \/><\/li><li>Die digitale Mitgliedschaft beinhaltet den Zugriff auf die Website der \u201epersolog Academy\u201c (onlineacademy.persolog.com) \u00fcber PC\/Mac\/Notebook, Smartphones und Tablets.<br \/><br \/><\/li><li>Eine vor\u00fcbergehende Unterbrechung der digitalen Mitgliedschaften ist nicht m\u00f6glich.<br \/><br \/><\/li><li>Die digitale Mitgliedschaft ist personenbezogen und bezieht sich ausschlie\u00dflich auf den vom Kunden benannten berechtigten Nutzer. Die \u00dcbertragung der Rechte an Dritte ist nicht gestattet.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f88fd8b e-flex e-con-boxed e-con e-parent\" data-id=\"f88fd8b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4bfe70a e-flex e-con-boxed e-con e-child\" data-id=\"4bfe70a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8560d25 elementor-widget elementor-widget-heading\" data-id=\"8560d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">IV. Verf\u00fcgbarkeit digitaler Inhalte<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f6a9d elementor-widget elementor-widget-text-editor\" data-id=\"25f6a9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Die \u00fcber das Internet abrufbaren Inhalte stehen dem Kunden grunds\u00e4tzlich jederzeit zur Verf\u00fcgung. Eine jederzeitige Verf\u00fcgbarkeit an 7 Tagen\/Woche und 24 Stunden\/Tag kann jedoch weder garantiert noch zugesichert werden.<br \/><br \/><\/li><li>Bei vor\u00fcbergehenden Unterbrechungen aufgrund notwendiger Wartungsarbeiten oder systembedingter St\u00f6rungen des Internets bei Drittanbietern oder Drittnutzerbetreibern sowie im Falle h\u00f6herer Gewalt kann der Zugang vor\u00fcbergehend unterbrochen werden.<br \/><br \/><\/li><li>Ein Anspruch auf bestimmte Inhalte besteht nicht. Wir sind jederzeit berechtigt, die bereitgestellten Inhalte zu entfernen, zu \u00e4ndern, zu verbessern und\/oder zu erg\u00e4nzen.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf8920a e-flex e-con-boxed e-con e-parent\" data-id=\"bf8920a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5168e7d e-flex e-con-boxed e-con e-child\" data-id=\"5168e7d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a64bcd elementor-widget elementor-widget-heading\" data-id=\"3a64bcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">V. Registrierung und Zugangsberechtigung <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-063432d elementor-widget elementor-widget-text-editor\" data-id=\"063432d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Digitale Mitgliedschaften erfordern eine Registrierung durch den Kunden. Der Kunde hat die zur Nutzung des Dienstes berechtigte Person mit seiner E-Mail-Adresse anzugeben.<br \/><br \/><\/li><li>Der Kunde erh\u00e4lt Zugangsdaten, um auf die digital bereitgestellten Inhalte zuzugreifen. Zugangsdaten sind sicher aufzubewahren und d\u00fcrfen nicht an Dritte weitergegeben werden. Die Nutzung durch vom Kunden eingesetzte Dritte ist gestattet, jedoch nur zur einmaligen und zeitlich begrenzten Nutzung im Rahmen einer konkreten Veranstaltung des Kunden.<br \/><br \/><\/li><li>Wir k\u00f6nnen einen Account sperren oder l\u00f6schen, wenn dieser missbr\u00e4uchlich genutzt wird oder \u00fcber den Account rechtswidrige, wettbewerbswidrige, strafrechtlich relevante oder sittenwidrige Handlungen begangen werden.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-693c36b e-flex e-con-boxed e-con e-parent\" data-id=\"693c36b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-768d3e9 e-flex e-con-boxed e-con e-child\" data-id=\"768d3e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-796434b elementor-widget elementor-widget-heading\" data-id=\"796434b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">VI. Preise und Zahlungsarten<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0405341 elementor-widget elementor-widget-text-editor\" data-id=\"0405341\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Es gelten die Preise unserer jeweils zum Zeitpunkt des Vertragsschlusses g\u00fcltigen Preisliste.<br \/><br \/><\/li><li>Wird der digitale Inhalt der Mitgliedschaft nach Vertragsschluss mehr als nur unwesentlich erweitert, sind wir berechtigt, die Preise angemessen, und zwar im Verh\u00e4ltnis zur erfolgten Erweiterung, zu erh\u00f6hen. Die Erh\u00f6hung wird mit Beginn des \u00fcbern\u00e4chsten Monats nach Zugang der \u00c4nderungsmitteilung beim Kunden wirksam. Der Kunde ist berechtigt, den Vertrag innerhalb von sechs Wochen nach Bekanntgabe der Preiserh\u00f6hung mit Wirkung zum Wirksamwerden der Preiserh\u00f6hung fristlos zu k\u00fcndigen. Macht der Kunde von diesem Recht keinen Gebrauch und wurde er in der Mitteilung \u00fcber die Preiserh\u00f6hung auf diese Rechtsfolge hingewiesen, wird der Vertrag zu den ge\u00e4nderten Preisen fortgef\u00fchrt.<br \/><br \/><\/li><li>Sofern sich aus der Auftragsbest\u00e4tigung nichts anderes ergibt, verstehen sich unsere Preise zuz\u00fcglich der jeweils g\u00fcltigen gesetzlichen Mehrwertsteuer.<br \/><br \/><\/li><li>Die Abwicklung des Vertragsverh\u00e4ltnisses erfolgt \u00fcber den Dienstleister digistore24 oder einen anderen von uns vor der Bestellung benannten Zahlungsdienstleister. Es gelten die dort aufgef\u00fchrten Zahlungsm\u00f6glichkeiten und Konditionen.<br \/><br \/><\/li><li>Bei Zahlungsverzug des Kunden sind wir berechtigt, den Zugang zur digitalen Mitgliedschaft zu sperren, bis alle f\u00e4lligen Forderungen aus der gesamten Gesch\u00e4ftsbeziehung mit dem Kunden, gleich aus welchem Rechtsgrund, vom Kunden beglichen sind. Dar\u00fcber hinaus sind wir berechtigt, Verzugszinsen in gesetzlicher H\u00f6he zu verlangen. Die Geltendmachung eines weitergehenden Verzugsschadens bleibt unber\u00fchrt.<br \/><br \/><\/li><li>Der Kunde kann nur mit einer von uns unbestrittenen oder rechtskr\u00e4ftig festgestellten Forderung gegen uns aufrechnen. Zur Aus\u00fcbung eines Zur\u00fcckbehaltungsrechts ist der Kunde nur insoweit befugt, als sein Gegenanspruch auf demselben Vertragsverh\u00e4ltnis beruht. Ein Zur\u00fcckbehaltungsrecht wegen Teilleistungen gem\u00e4\u00df \u00a7 320 Abs. 1 BGB steht dem Kunden nicht zu. 2 BGB.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc1c530 e-flex e-con-boxed e-con e-parent\" data-id=\"dc1c530\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0afa044 e-flex e-con-boxed e-con e-child\" data-id=\"0afa044\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6f2287 elementor-widget elementor-widget-heading\" data-id=\"c6f2287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">VII. Gew\u00e4hrleistung und Haftung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5de15f2 elementor-widget elementor-widget-text-editor\" data-id=\"5de15f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Es gilt die gesetzliche Gew\u00e4hrleistung.<br \/><br \/><\/li><li>Wir werden technische M\u00e4ngel auf der Website der \u201epersolog Academy\u201c innerhalb angemessener Frist beheben. Unsere Verantwortung erstreckt sich hierbei nur auf den \u00dcbergabepunkt der von uns betriebenen Systeme an das Internet, nicht jedoch auf dar\u00fcber hinausgehende Systeme und Daten\u00fcbertragungsleitungen des Kunden.<br \/><br \/><\/li><li>F\u00fcr den Inhalt \u00fcbernehmen wir keine Gew\u00e4hr. Der Kunde hat keinen Anspruch auf bestimmte Inhalte. Wir sind jederzeit berechtigt, die bereitgestellten Inhalte zu entfernen, zu \u00e4ndern, zu verbessern und\/oder zu erg\u00e4nzen.<br \/><br \/><\/li><li>Bei der Auswahl und Pflege der Inhalte wenden wir die \u00fcbliche Sorgfalt an. F\u00fcr die Vollst\u00e4ndigkeit, Richtigkeit und Aktualit\u00e4t der Inhalte k\u00f6nnen wir jedoch keine Gew\u00e4hr \u00fcbernehmen.<br \/><br \/><\/li><li>Der Kunde ist f\u00fcr die unverz\u00fcgliche Anzeige etwaiger M\u00e4ngel, St\u00f6rungen oder Sch\u00e4den verantwortlich.<br \/><br \/><\/li><li>Wir haften nach den gesetzlichen Bestimmungen, sofern der Kunde Schadens- oder Aufwendungsersatzanspr\u00fcche geltend macht, die auf Vorsatz oder grober Fahrl\u00e4ssigkeit, einschlie\u00dflich Vorsatz oder grober Fahrl\u00e4ssigkeit unserer Vertreter oder Erf\u00fcllungsgehilfen beruhen. Soweit uns keine vors\u00e4tzliche Vertragsverletzung angelastet wird, ist die Schadensersatzhaftung auf den vorhersehbaren, typischerweise eintretenden Schaden begrenzt.<br \/><br \/><\/li><li>Wir haften nach den gesetzlichen Bestimmungen, sofern wir schuldhaft eine wesentliche Vertragspflicht verletzen; in diesem Fall ist jedoch die Schadensersatzhaftung auf den bei Vertragsschluss vorhersehbaren, typischerweise eintretenden Schaden begrenzt.<br \/><br \/><\/li><li>Die Haftung wegen schuldhafter Verletzung des Lebens, des K\u00f6rpers oder der Gesundheit bleibt unber\u00fchrt; dies gilt auch f\u00fcr die zwingende Haftung nach dem Produkthaftungsgesetz.<br \/><br \/><\/li><li>Soweit vorstehend oder in unseren Nutzungsbedingungen nichts Abweichendes geregelt ist, ist die Haftung \u2013 ohne R\u00fccksicht auf die Rechtsnatur des geltend gemachten Anspruchs \u2013 ausgeschlossen. Dies gilt insbesondere f\u00fcr Schadensersatzanspr\u00fcche aus Verschulden bei Vertragsschluss, aus sonstigen Pflichtverletzungen oder aus deliktischen Anspr\u00fcchen auf Ersatz von Sachsch\u00e4den gem\u00e4\u00df \u00a7 823 BGB.<br \/><br \/><\/li><li>Die pers\u00f6nliche Haftung unserer gesetzlichen Vertreter, Erf\u00fcllungsgehilfen und Mitarbeiter f\u00fcr von ihnen leicht fahrl\u00e4ssig verursachte Sch\u00e4den ist ausgeschlossen. Soweit unsere Schadensersatzhaftung ausgeschlossen oder eingeschr\u00e4nkt ist, gilt dies auch im Hinblick auf die pers\u00f6nliche Schadensersatzhaftung der vorgenannten Personen.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb99ba2 e-flex e-con-boxed e-con e-parent\" data-id=\"cb99ba2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-291df97 e-flex e-con-boxed e-con e-child\" data-id=\"291df97\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c24be9 elementor-widget elementor-widget-heading\" data-id=\"3c24be9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">VIII. Dauer und Beendigung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a0fb07 elementor-widget elementor-widget-text-editor\" data-id=\"2a0fb07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Die Laufzeit der digitalen Mitgliedschaften ergibt sich aus dem jeweiligen Vertrag. Die Vertragslaufzeit verl\u00e4ngert sich automatisch um die jeweils vereinbarte Laufzeit, es sei denn, die Mitgliedschaft wurde von einer der Vertragsparteien bis zum letzten Mal schriftlich, also in Schrift- oder Textform (z. B. Brief, E-Mail, Fax), gek\u00fcndigt Sp\u00e4testens am Tag der vereinbarten Laufzeit.<br \/><br \/><\/li><li>Das Recht zur K\u00fcndigung des Vertrages aus wichtigem Grund bleibt unber\u00fchrt. Ein wichtiger Grund liegt f\u00fcr uns insbesondere dann vor, wenn (i) der Kunde schwerwiegend oder trotz Abmahnung durch uns wiederholt gegen diese Nutzungsbedingungen oder sonstige Vertragspflichten versto\u00dfen hat, (ii) der Kunde den Zugang unbefugt nutzt oder zul\u00e4sst von Dritten genutzt werden, (iii) die digitalen Inhalte rechtswidrig nutzt, (iv) der Kunde seinen Zahlungsverpflichtungen trotz zweimaliger Mahnung nicht nachkommt, (v) sich die Verm\u00f6gensverh\u00e4ltnisse des Kunden wesentlich verschlechtert haben oder (vi) zumindest \u00fcber das Verm\u00f6gen des Kunden ein vorl\u00e4ufiges Insolvenzverfahren er\u00f6ffnet oder mangels Masse abgewiesen wurde.<br \/><br \/><\/li><li>Bei Beendigung des Vertrages werden wir den Zugang des Kunden zu den digitalen Mitgliedschaften mit sofortiger Wirkung sperren.<br \/><br \/><\/li><li>Sofern der Kunde eine vorzeitige Vertragsbeendigung zu vertreten hat, haben wir au\u00dferdem Anspruch auf Schadensersatz, der sich auch auf den Ersatz von Sonderkonditionen erstrecken kann, die dem Kunden oder werbenden Dritten bei Vertragsschluss einger\u00e4umt wurden.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb80953 e-flex e-con-boxed e-con e-parent\" data-id=\"fb80953\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-01cdf2a e-flex e-con-boxed e-con e-child\" data-id=\"01cdf2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7cbaad elementor-widget elementor-widget-heading\" data-id=\"c7cbaad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">IX. \u00c4nderungen und \u00dcbertragungen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f16d5e6 elementor-widget elementor-widget-text-editor\" data-id=\"f16d5e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>\u00c4nderungen der Rechnungsadresse, des bestellten Mitgliedschaftsmoduls oder sonstiger Daten des Kunden sind uns mitzuteilen und k\u00f6nnen fr\u00fchestens f\u00fcnf Tage nach Erhalt ber\u00fccksichtigt werden. \u00c4nderungen der Zahlungsart \u2013 mit Ausnahme von Konto\u00e4nderungen \u2013 sind erst nach Ablauf der gew\u00e4hlten Zahlungsfrist m\u00f6glich.<br \/><br \/><\/li><li>Die \u00dcbertragung der Mitgliedschaft auf einen anderen Kunden bedarf unserer Zustimmung. Ein \u00dcberweisungsantrag beider Kunden ist in Textform an uns zu richten. Mit der Durchf\u00fchrung der \u00c4nderung gilt unsere Zustimmung als erteilt.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13754bc e-flex e-con-boxed e-con e-parent\" data-id=\"13754bc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4931623 e-flex e-con-boxed e-con e-child\" data-id=\"4931623\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5eef46a elementor-widget elementor-widget-heading\" data-id=\"5eef46a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">X. Urheber- und Eigentumsrechte<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9925ff1 elementor-widget elementor-widget-text-editor\" data-id=\"9925ff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Die im Rahmen der digitalen Mitgliedschaft zur Verf\u00fcgung gestellten Inhalte unterliegen dem Schutz des Urheberrechts oder anderer Schutzrechte von uns oder Dritten. F\u00fcr die Nutzung der digitalen Mitgliedschaften erwirbt der Kunde, vorbehaltlich der Zahlung der geschuldeten und geschuldeten Verg\u00fctung, f\u00fcr sich und im Umfang seiner Bestellung und der einzelvertraglichen Vereinbarung ggf. auch f\u00fcr andere berechtigte Nutzer die an den jeweiligen digitalen Inhalten f\u00fcr eigene Zwecke ein einfaches, nicht ausschlie\u00dfliches, nicht unterlizenzierbares, nicht auf Dritte \u00fcbertragbares und auf die Vertragslaufzeit beschr\u00e4nktes Nutzungsrecht. Das Nutzungsrecht berechtigt den Kunden, die digitalen Inhalte zu lesen bzw. anzusehen.<\/li><\/ol><ol start=\"2\"><li>Jegliche Nutzung, die \u00fcber die in Ziffer XI.1 beschriebene Nutzung hinausgeht. ist ausgeschlossen und bedarf der vorherigen gesonderten schriftlichen Zustimmung des jeweiligen Rechteinhabers, sofern eine solche Nutzung nicht durch zwingende gesetzliche Vorschriften zul\u00e4ssig ist. Insbesondere ist es dem Kunden oder anderen berechtigten Nutzern untersagt, die digitalen Inhalte \u2013 auch auszugsweise \u2013 zu vervielf\u00e4ltigen, Urheberrechtsvermerke oder Markennamen zu entfernen, die digitalen Inhalte zu modifizieren oder zu ver\u00e4ndern, die digitalen Inhalte auf andere Datentr\u00e4ger oder Netzwerke zu kopieren sowie Vervielf\u00e4ltigungen anzufertigen und zu nutzen und Weitergabe, Zug\u00e4nglichmachung oder jede Form der kommerziellen Nutzung, sei es entgeltlich oder unentgeltlich. Der Kunde darf keine Mittel zur \u00dcberwindung oder Umgehung dieser Ma\u00dfnahmen einsetzen.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20cd61c e-flex e-con-boxed e-con e-parent\" data-id=\"20cd61c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0497a96 e-flex e-con-boxed e-con e-child\" data-id=\"0497a96\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a3376 elementor-widget elementor-widget-heading\" data-id=\"c1a3376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">XI. Datenschutz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48661f1 elementor-widget elementor-widget-text-editor\" data-id=\"48661f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Die hierf\u00fcr erforderlichen Kunden- und Lieferdaten werden von uns entsprechend den Bestimmungen des deutschen Datenschutzrechts erhoben, verarbeitet und gespeichert. Die Daten werden zur Vertragserf\u00fcllung genutzt und in diesem Zusammenhang gegebenenfalls auch an Dritte weitergegeben.<br \/><br \/><\/li><li>Der Kunde kann der \u00fcber die Vertragserf\u00fcllung hinausgehenden Datenverwendung jederzeit in Textform widersprechen, z. B. per E-Mail an datenschutz@persolog.com.<br \/><br \/><\/li><li>Erg\u00e4nzend gilt unsere Datenschutzerkl\u00e4rung<br \/><a style=\"font-size: 16px; background-color: #ffffff;\" href=\"https:\/\/www.persolog.de\/allgemeine-geschaeftsbedingungen\/datenschutz\/\">https:\/\/www.persolog.de\/allgemeine-geschaeftsbedingungen\/datenschutz\/<\/a><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4517d6 e-flex e-con-boxed e-con e-parent\" data-id=\"e4517d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6761f70 e-flex e-con-boxed e-con e-child\" data-id=\"6761f70\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c1ce47 elementor-widget elementor-widget-heading\" data-id=\"5c1ce47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">XII. Erf\u00fcllungsort, Gerichtsstand und anwendbares Recht\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc37c8 elementor-widget elementor-widget-text-editor\" data-id=\"7bc37c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Erf\u00fcllungsort und Gerichtsstand f\u00fcr alle sich aus dem Vertragsverh\u00e4ltnis mittelbar oder unmittelbar ergebenden Verpflichtungen ist der Sitz unseres Gesch\u00e4ftssitzes in 75196 Remchingen. Wir sind auch berechtigt, am Sitz des Kunden zu klagen.<\/li><li>Es gilt das Recht der Bundesrepublik Deutschland.<\/li><\/ol><p>Stand: September 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>General Terms and Conditions for orders and bookings with persolog GmbH for consumers and bussinesses Status: 01.09.2025 I. Scope All offers, deliveries and other services with regard to orders\/bookings of goods with us are subject to the following General Terms and Conditions (hereinafter only &#8220;Terms and Conditions&#8221;) in the version valid at the time of [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4073","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>General Terms and Conditions - persolog Homepage<\/title>\n<meta name=\"description\" content=\"Read and understand persolog&#039;s General Terms &amp; Conditions. Learn about our policies, usage guidelines, and important legal information.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/persolog.com\/de\/allgemeine-geschaeftsbedingungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General Terms and Conditions\" \/>\n<meta property=\"og:description\" content=\"Read and understand persolog&#039;s General Terms &amp; Conditions. Learn about our policies, usage guidelines, and important legal information.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/persolog.com\/de\/allgemeine-geschaeftsbedingungen\/\" \/>\n<meta property=\"og:site_name\" content=\"persolog Homepage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T10:07:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"53\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/persolog.com\\\/general-terms-conditions\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/general-terms-conditions\\\/\",\"name\":\"General Terms and Conditions - persolog Homepage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\"},\"datePublished\":\"2023-07-11T13:20:35+00:00\",\"dateModified\":\"2026-04-14T10:07:28+00:00\",\"description\":\"Read and understand persolog's General Terms & Conditions. Learn about our policies, usage guidelines, and important legal information.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/general-terms-conditions\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/persolog.com\\\/general-terms-conditions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/persolog.com\\\/general-terms-conditions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/persolog.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General Terms and Conditions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"name\":\"persolog\u00ae Homepage\",\"description\":\"Develop organizations through people\",\"publisher\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/persolog.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\",\"name\":\"persolog\u00ae GmbH\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"contentUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"width\":150,\"height\":36,\"caption\":\"persolog\u00ae GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/persolog.persoenlichkeitsentwicklung\\\/?locale=de_DE\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/persolog-gmbh\",\"https:\\\/\\\/www.instagram.com\\\/persolog_\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Allgemeine Gesch\u00e4ftsbedingungen - persolog Homepage","description":"Lese und verstehe die Allgemeinen Gesch\u00e4ftsbedingungen von persolog. Erfahre mehr \u00fcber unsere Richtlinien, Nutzungsbestimmungen und wichtige rechtliche Informationen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/persolog.com\/de\/allgemeine-geschaeftsbedingungen\/","og_locale":"de_DE","og_type":"article","og_title":"General Terms and Conditions","og_description":"Read and understand persolog's General Terms & Conditions. Learn about our policies, usage guidelines, and important legal information.","og_url":"https:\/\/persolog.com\/de\/allgemeine-geschaeftsbedingungen\/","og_site_name":"persolog Homepage","article_publisher":"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","article_modified_time":"2026-04-14T10:07:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"53\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/persolog.com\/general-terms-conditions\/","url":"https:\/\/persolog.com\/general-terms-conditions\/","name":"Allgemeine Gesch\u00e4ftsbedingungen - persolog Homepage","isPartOf":{"@id":"https:\/\/persolog.com\/#website"},"datePublished":"2023-07-11T13:20:35+00:00","dateModified":"2026-04-14T10:07:28+00:00","description":"Lese und verstehe die Allgemeinen Gesch\u00e4ftsbedingungen von persolog. Erfahre mehr \u00fcber unsere Richtlinien, Nutzungsbestimmungen und wichtige rechtliche Informationen.","breadcrumb":{"@id":"https:\/\/persolog.com\/general-terms-conditions\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/persolog.com\/general-terms-conditions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/persolog.com\/general-terms-conditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/persolog.com\/"},{"@type":"ListItem","position":2,"name":"General Terms and Conditions"}]},{"@type":"WebSite","@id":"https:\/\/persolog.com\/#website","url":"https:\/\/persolog.com\/","name":"persolog\u00ae Startseite","description":"Organisationen durch Menschen entwickeln","publisher":{"@id":"https:\/\/persolog.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/persolog.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/persolog.com\/#organization","name":"persolog\u00ae GmbH","url":"https:\/\/persolog.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/","url":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","contentUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","width":150,"height":36,"caption":"persolog\u00ae GmbH"},"image":{"@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","https:\/\/de.linkedin.com\/company\/persolog-gmbh","https:\/\/www.instagram.com\/persolog_\/"]}]}},"_links":{"self":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/pages\/4073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/comments?post=4073"}],"version-history":[{"count":131,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/pages\/4073\/revisions"}],"predecessor-version":[{"id":34605,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/pages\/4073\/revisions\/34605"}],"wp:attachment":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/media?parent=4073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}