{"id":11004,"date":"2015-09-02T14:00:13","date_gmt":"2015-09-02T12:00:13","guid":{"rendered":"https:\/\/persolog.com\/blog\/7-fehler-die-sie-im-verkaufsgesprach-meiden-sollten\/"},"modified":"2025-07-07T10:01:22","modified_gmt":"2025-07-07T08:01:22","slug":"7-fehler-die-sie-im-verkaufsgesprach-meiden-sollten","status":"publish","type":"post","link":"https:\/\/persolog.com\/de\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/","title":{"rendered":"7 Fehler, die du im Verkaufsgespr\u00e4ch meiden solltest"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11004\" class=\"elementor elementor-11004\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3304d568 e-flex e-con-boxed e-con e-parent\" data-id=\"3304d568\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-158bcdf8 elementor-widget elementor-widget-text-editor\" data-id=\"158bcdf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Viele von uns haben es schon erlebt: Ein vielversprechendes Gespr\u00e4ch mit einem potenziellen Neukunden steht an. Aber die Erwartung erf\u00fcllt sich nicht, denn ein Abschluss kommt nicht zustande. Die Gr\u00fcnde daf\u00fcr sind vielf\u00e4ltig, aber eines ist sicher: Verkaufsgespr\u00e4che scheitern oft an bestimmten Fehlern, die leicht vermieden werden k\u00f6nnten. In diesem Artikel werfen wir einen Blick auf sieben typische Fehler, die den erfolgreichen Abschluss eines Verkaufsgespr\u00e4chs gef\u00e4hrden. Erfahre, wie du diese Stolperfallen umgehen kannst, um in Zukunft in deinen Verkaufsgespr\u00e4chen zu gl\u00e4nzen.<\/p><h2>Was ist eigentlich Verkaufen?<\/h2><p>Verkaufen ist viel mehr als nur der perfekte Vertragsabschluss zwischen verschiedenen Personen. Verkaufen ist in erster Linie ein zwischenmenschlicher Prozess, bei dem du die Regeln zwischenmenschlicher Kommunikation auf jeden Fall beachten solltest. Wenn du unreflektiert in ein Verkaufsgespr\u00e4ch startest, ist ein Abschluss nur schwer zu erreichen. Die folgenden Fehler zeigen dir, woran Verkaufsgespr\u00e4che oft scheitern.<\/p><h2>Verkaufsgespr\u00e4ch: Vermeide diese 7 Fehler<\/h2><h3>Fehler 1: Unklare Nutzenkommunikation<\/h3><p>Wenn du nicht klar vermitteln kannst, welchen Nutzen dein Produkt oder deine Dienstleistung f\u00fcr den Kunden bietet, wird es schwer, das Interesse des Kunden zu wecken und einen Abschluss zu erzielen.<\/p><p><strong>Unser Tipp:<\/strong> Achte darauf, dass du den klaren Nutzen deines Produkts oder deiner Dienstleistung in verst\u00e4ndlichen und pr\u00e4gnanten Aussagen darstellen kannst, die auf die individuellen Bed\u00fcrfnisse und Herausforderungen deiner Kunden zugeschnitten sind. Nutze konkrete Beispiele und Fallstudien, um die positiven Auswirkungen deines Angebots zu verdeutlichen. Betone, wie es die Probleme deiner Kunden l\u00f6sen und ihren Mehrwert steigern kann.<\/p><h3>Fehler 2: Auf Mitbewerber schimpfen<\/h3><p>Selbstverst\u00e4ndlich werden Kunden sich auch Angebote von deiner Konkurrenz einholen. In vielen Unternehmen mit zentralem Einkauf ist das sogar Vorschrift. Vermeide den Drang, deinen Mitbewerber schlecht zu machen. Das wirkt unseri\u00f6s und kann dich den Auftrag kosten.<\/p><p><strong>Unser Tipp:<\/strong> Es spricht nichts dagegen, die Konkurrenz auch mal zu loben. Sei selbstbewusst und zeige deinem Gegen\u00fcber, dass du keine Angst vor deinen Mitbewerbern hast. Das vermittelt den Eindruck, dass du von deinem eigenen Angebot \u00fcberzeugt bist.<\/p><h3>Fehler 3: Du kennst deine St\u00e4rken nicht<\/h3><p>Hast du schon mal dar\u00fcber nachgedacht, wie du als Verk\u00e4ufer tickst? Wenn du deine eigene Verk\u00e4uferpers\u00f6nlichkeit nicht reflektierst, wird es schwierig, besser zu werden, deine Schwachstellen zu erkennen und gezielt daran zu arbeiten.<\/p><p><strong>Unser Tipp:<\/strong> Nutze ein Selbstreflexions-Tool, um deinem Verhalten als Verk\u00e4ufer auf die Spur zu kommen. Denn nur wenn du dir dar\u00fcber bewusst bist, was du gut kannst und worin du noch besser werden kannst, hast du die Chance gezielt besser zu werden. Daf\u00fcr kannst du zum Beispiel unseren Online-Bericht <a href=\"https:\/\/shop.persolog.com\/persolog-Verkaufen-im-Fokus-online\/IN118\">Verkaufen im Fokus nutzen<\/a>. Auf genau 20 Seiten bekommst du eine individualisierte Analyse deines Verkaufsverhaltens, und zwar kurz und pr\u00e4gnant beschrieben \u2013 sowie viele Tipps, wie du deine Verk\u00e4ufe steigern kannst. Das ganze Profil basiert auf D, I, S &amp; G, anders gesagt: auf dem <a href=\"https:\/\/persolog.com\/de\/persolog-personality-factor-model\/\">persolog\u00ae Pers\u00f6nlichkeits-Modell<\/a>.<\/p><h3>Fehler 4: Fehlendes Interesse am Kunden<\/h3><p>F\u00fchre keine Verkaufsgespr\u00e4che nach Schema F durch. Wenn du nur \u00fcbliche S\u00e4tze herunterspulst, wirkt das f\u00fcr den Kunden so, als w\u00fcrde dir jegliches Interesse fehlen. Nur gut vorbereitete Verk\u00e4ufer k\u00f6nnen auf die W\u00fcnsche und Bed\u00fcrfnisse ihrer Kunden eingehen.<\/p><p><strong>Unser Tipp:<\/strong> Recherchiere online, bevor du mit deinem Kunden sprichst. Je mehr du \u00fcber deinen Kunden und seine Produkte\/seine Dienstleistungen wei\u00dft, desto professioneller wirkt der Gespr\u00e4chsverlauf \u2013 und desto sicherer f\u00fchlst du dich auch w\u00e4hrend des Gespr\u00e4chs. Gehe individuell auf den Kunden ein. \u201eFragen, fragen, fragen\u201c lautet hier das Motto. So kannst du dein Angebot direkt an den Kunden anpassen und auch deine Argumentation auf die Kundenpers\u00f6nlichkeit abstimmen. Gerade, wenn dein Verkaufsprozess aus mehreren Gespr\u00e4chen besteht, kann der <a href=\"https:\/\/shop.persolog.com\/Strategieplaner-fuer-Verkauf-und-Service\/PL106\">persolog\u00ae Strategieplaner f\u00fcr Verkauf und Service<\/a> dir helfen, deinen Kunden richtig einzusch\u00e4tzen und deine Kommunikation auf ihn abzustimmen. Dies erh\u00f6ht die Wahrscheinlichkeit eines Abschlusses erheblich.<\/p><h3>Fehler 5: Zu viel Reden, zu wenig Zuh\u00f6ren<\/h3><p>Ein h\u00e4ufiger Fehler ist es, als Verk\u00e4ufer zu viel zu reden. Stelle nicht dich selbst in den Fokus des Gespr\u00e4chs, sondern klar deinen Kunden. Es wird dich nicht weiterbringen, wenn dein Redeanteil deutlich \u00fcberwiegt.<\/p><p><strong>Unser Tipp:<\/strong> Ein gutes Verkaufsgespr\u00e4ch erfordert aktives Zuh\u00f6ren, um die richtigen L\u00f6sungen anbieten zu k\u00f6nnen. Es gilt, auf die Kunden-Bed\u00fcrfnisse einzugehen und ihn mit deinen Produkten\/Dienstleistungen zu unterst\u00fctzen. So erf\u00e4hrst du, was dein Kunde m\u00f6chte und wie dein Kunde tickt \u2013 nur so erh\u00e4ltst du die Chance auf den Auftrag.<\/p><h3>Fehler 6: Mangelndes Selbstvertrauen<\/h3><p>Wer unsicher im Verkaufsgespr\u00e4ch auftritt, hat schlechte Karten. Dein Kunde m\u00f6chte sich auf dich verlassen und wird sich kaum mit vagen Aussagen zufriedenstellen, wie \u201em\u00fcssen wir hinbekommen\u201c, \u201evielleicht ja\u201c oder \u201eeigentlich schon\u201c.<\/p><p><strong>Unser Tipp:<\/strong> Selbstvertrauen beginnt vor dem eigentlichen Gespr\u00e4ch \u2013 und zwar schon bei der Begr\u00fc\u00dfung. Sei dir auch bewusst \u00fcber deine nonverbale Kommunikation. Zeige Offenheit, begr\u00fc\u00dfe deinen Kunden bei einem Treffen vor Ort mit einem klaren H\u00e4ndedruck und schaue ihm\/ihr in die Augen. Zeige deinem Gespr\u00e4chspartner w\u00e4hrend des Gespr\u00e4chs, dass du die ben\u00f6tigten Leistungen zu 100 % erf\u00fcllst.<\/p><h3>Fehler 7: Das Gespr\u00e4ch ohne Follow-Up abschlie\u00dfen<\/h3><p>Der Klassiker: Das Gespr\u00e4ch ist gut verlaufen, aber dein Kunde will sich nicht festlegen und fordert Bedenkzeit. Es ist v\u00f6llig legitim, dass Menschen Bedenkzeit brauchen. Wenn du das Gespr\u00e4ch jedoch ohne Plan abschlie\u00dft, ist die Wahrscheinlichkeit gro\u00df, dass sich das Angebot im Sande verl\u00e4uft.<\/p><p><strong>Unser Tipp:<\/strong> Wenn du am Ende des Gespr\u00e4chs um Bedenkzeit gebeten wirst, frage nach den Gr\u00fcnden. So kannst du verstehen, wo noch Fragen, Unklarheiten oder Bedenken sind und das in deiner Kommunikation ber\u00fccksichtigen. Vereinbare am Ende des Gespr\u00e4chs unbedingt einen Folgetermin, um zeitnah wieder im Gespr\u00e4ch zu sein. Manchmal hilft schon ein Satz am Ende, wie \u201eIch freue mich auf unsere Zusammenarbeit\u201c, um den Abschluss zu beschleunigen.<\/p><p>Wenn du diese Fehler vermeidest und unsere Tipps beachtest, erh\u00f6hst du die Chance auf einen Verkaufsabschluss. Und wie immer gilt: \u00dcben, \u00fcben, \u00fcben! Mit jedem Verkaufsgespr\u00e4ch gewinnst du an Sicherheit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-792a99c elementor-widget elementor-widget-text-editor\" data-id=\"792a99c\" data-element_type=\"widget\" data-e-type=\"widget\" data-no-translation=\"\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Du m\u00f6chtest mehr erfahren?<\/h3><p>Wenn du Verkaufsstrategien entwicklen und Verkaufsst\u00e4rken identifizieren sowie ausbauen m\u00f6chtest, dann empfehlen wir dir<strong><a href=\"https:\/\/shop.persolog.com\/persolog-Sales-Profil\/DE-IN114-07-25-V1.0\"> unser Sales-Profil:<\/a><\/strong> finde heraus, wie du dich im Verkauf verh\u00e4ltst und was f\u00fcr eine Rolle hier DISG spielt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54f3e0b elementor-widget elementor-widget-text-editor\" data-id=\"54f3e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Schau unser Video, um einen tieferen Einblick ins Thema zu bekommen:<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7651204 elementor-widget elementor-widget-video\" data-id=\"7651204\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=RnAT7JUPmdI&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ein vielversprechendes Gespr\u00e4ch mit einem neuen Kunden bahnt sich an. Die Erwartung wird jedoch nicht erf\u00fcllt, denn ein Gesch\u00e4ft kommt nicht zustande. Eines ist sicher: Verkaufsgespr\u00e4che scheitern oft an bestimmten Fehlern, die leicht zu vermeiden w\u00e4ren.<\/p>","protected":false},"author":1,"featured_media":20120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23],"tags":[989,938,986,477,506,1007,228,692,64,65,237,1019],"class_list":["post-11004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personality","tag-angebot","tag-anpassungsfahigkeit","tag-arbeitswelt","tag-beruflicher-erfolg","tag-erfolge","tag-erfolgreich","tag-erfolgsfaktor","tag-verhaltenskomponenten","tag-verkauf","tag-verkaufen","tag-verkaeufer","tag-verkaufsstrategie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Avoid these Mistakes in Sales Conversations \u2013 persolog Blog<\/title>\n<meta name=\"description\" content=\"Blog | Avoid these 7 mistakes in sales conversations and get tips to increase the chance of closing a sale. Read more now\u00bb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/persolog.com\/de\/blog\/7-fehler-die-sie-im-verkaufsgesprach-meiden-sollten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 Mistakes to Avoid in Sales Conversations\" \/>\n<meta property=\"og:description\" content=\"Blog | Avoid these 7 mistakes in sales conversations and get tips to increase the chance of closing a sale. Read more now\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/persolog.com\/de\/blog\/7-fehler-die-sie-im-verkaufsgesprach-meiden-sollten\/\" \/>\n<meta property=\"og:site_name\" content=\"persolog Homepage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-02T12:00:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T08:01:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/persolog.com\/wp-content\/uploads\/2015\/09\/Fotolia_200718227_Subscription_Monthly_M.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1603\" \/>\n\t<meta property=\"og:image:height\" content=\"1186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"persolog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"persolog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/\"},\"author\":{\"name\":\"persolog\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/person\\\/f281c4aed52bf5e01f0bb326bbcf1ae9\"},\"headline\":\"7 Mistakes to Avoid in Sales Conversations\",\"datePublished\":\"2015-09-02T12:00:13+00:00\",\"dateModified\":\"2025-07-07T08:01:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/\"},\"wordCount\":1028,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Fotolia_200718227_Subscription_Monthly_M.jpg\",\"keywords\":[\"Angebot\",\"Anpassungsf\u00e4higkeit\",\"Arbeitswelt\",\"beruflicher Erfolg\",\"Erfolge\",\"erfolgreich\",\"Erfolgsfaktor\",\"Verhaltenskomponenten\",\"Verkauf\",\"Verkaufen\",\"Verk\u00e4ufer\",\"Verkaufsstrategie\"],\"articleSection\":[\"Personality\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/\",\"name\":\"Avoid these Mistakes in Sales Conversations \u2013 persolog Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Fotolia_200718227_Subscription_Monthly_M.jpg\",\"datePublished\":\"2015-09-02T12:00:13+00:00\",\"dateModified\":\"2025-07-07T08:01:22+00:00\",\"description\":\"Blog | Avoid these 7 mistakes in sales conversations and get tips to increase the chance of closing a sale. Read more now\u00bb\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Fotolia_200718227_Subscription_Monthly_M.jpg\",\"contentUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Fotolia_200718227_Subscription_Monthly_M.jpg\",\"width\":1603,\"height\":1186,\"caption\":\"7 Fehler, die du im Verkaufsgespr\u00e4ch meiden solltest\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/7-mistakes-you-should-avoid-in-sales-conversations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/persolog.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 Mistakes to Avoid in Sales Conversations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"name\":\"persolog\u00ae Homepage\",\"description\":\"Develop organizations through people\",\"publisher\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/persolog.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\",\"name\":\"persolog\u00ae GmbH\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"contentUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"width\":150,\"height\":36,\"caption\":\"persolog\u00ae GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/persolog.persoenlichkeitsentwicklung\\\/?locale=de_DE\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/persolog-gmbh\",\"https:\\\/\\\/www.instagram.com\\\/persolog_\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/person\\\/f281c4aed52bf5e01f0bb326bbcf1ae9\",\"name\":\"persolog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g\",\"caption\":\"persolog\"},\"sameAs\":[\"https:\\\/\\\/rev-proxy-other.prod.persolog.online\"],\"url\":\"https:\\\/\\\/persolog.com\\\/de\\\/blog\\\/author\\\/persolog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vermeiden Sie diese Fehler in Verkaufsgespr\u00e4chen - persolog Blog","description":"Blog | Vermeiden Sie diese 7 Fehler in Verkaufsgespr\u00e4chen und erhalten Sie Tipps, um die Chance auf einen Verkaufsabschluss zu erh\u00f6hen. Jetzt mehr lesen\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/persolog.com\/de\/blog\/7-fehler-die-sie-im-verkaufsgesprach-meiden-sollten\/","og_locale":"de_DE","og_type":"article","og_title":"7 Mistakes to Avoid in Sales Conversations","og_description":"Blog | Avoid these 7 mistakes in sales conversations and get tips to increase the chance of closing a sale. Read more now\u00bb","og_url":"https:\/\/persolog.com\/de\/blog\/7-fehler-die-sie-im-verkaufsgesprach-meiden-sollten\/","og_site_name":"persolog Homepage","article_publisher":"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","article_published_time":"2015-09-02T12:00:13+00:00","article_modified_time":"2025-07-07T08:01:22+00:00","og_image":[{"width":1603,"height":1186,"url":"https:\/\/persolog.com\/wp-content\/uploads\/2015\/09\/Fotolia_200718227_Subscription_Monthly_M.jpg","type":"image\/jpeg"}],"author":"persolog","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"persolog","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#article","isPartOf":{"@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/"},"author":{"name":"persolog","@id":"https:\/\/persolog.com\/#\/schema\/person\/f281c4aed52bf5e01f0bb326bbcf1ae9"},"headline":"7 Mistakes to Avoid in Sales Conversations","datePublished":"2015-09-02T12:00:13+00:00","dateModified":"2025-07-07T08:01:22+00:00","mainEntityOfPage":{"@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/"},"wordCount":1028,"commentCount":1,"publisher":{"@id":"https:\/\/persolog.com\/#organization"},"image":{"@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#primaryimage"},"thumbnailUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2015\/09\/Fotolia_200718227_Subscription_Monthly_M.jpg","keywords":["Angebot","Anpassungsf\u00e4higkeit","Arbeitswelt","beruflicher Erfolg","Erfolge","erfolgreich","Erfolgsfaktor","Verhaltenskomponenten","Verkauf","Verkaufen","Verk\u00e4ufer","Verkaufsstrategie"],"articleSection":["Personality"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/","url":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/","name":"Vermeiden Sie diese Fehler in Verkaufsgespr\u00e4chen - persolog Blog","isPartOf":{"@id":"https:\/\/persolog.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#primaryimage"},"image":{"@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#primaryimage"},"thumbnailUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2015\/09\/Fotolia_200718227_Subscription_Monthly_M.jpg","datePublished":"2015-09-02T12:00:13+00:00","dateModified":"2025-07-07T08:01:22+00:00","description":"Blog | Vermeiden Sie diese 7 Fehler in Verkaufsgespr\u00e4chen und erhalten Sie Tipps, um die Chance auf einen Verkaufsabschluss zu erh\u00f6hen. Jetzt mehr lesen\"","breadcrumb":{"@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#primaryimage","url":"https:\/\/persolog.com\/wp-content\/uploads\/2015\/09\/Fotolia_200718227_Subscription_Monthly_M.jpg","contentUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2015\/09\/Fotolia_200718227_Subscription_Monthly_M.jpg","width":1603,"height":1186,"caption":"7 Fehler, die du im Verkaufsgespr\u00e4ch meiden solltest"},{"@type":"BreadcrumbList","@id":"https:\/\/persolog.com\/blog\/7-mistakes-you-should-avoid-in-sales-conversations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/persolog.com\/"},{"@type":"ListItem","position":2,"name":"7 Mistakes to Avoid in Sales Conversations"}]},{"@type":"WebSite","@id":"https:\/\/persolog.com\/#website","url":"https:\/\/persolog.com\/","name":"persolog\u00ae Startseite","description":"Organisationen durch Menschen entwickeln","publisher":{"@id":"https:\/\/persolog.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/persolog.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/persolog.com\/#organization","name":"persolog\u00ae GmbH","url":"https:\/\/persolog.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/","url":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","contentUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","width":150,"height":36,"caption":"persolog\u00ae GmbH"},"image":{"@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","https:\/\/de.linkedin.com\/company\/persolog-gmbh","https:\/\/www.instagram.com\/persolog_\/"]},{"@type":"Person","@id":"https:\/\/persolog.com\/#\/schema\/person\/f281c4aed52bf5e01f0bb326bbcf1ae9","name":"persolog","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g","caption":"persolog"},"sameAs":["https:\/\/rev-proxy-other.prod.persolog.online"],"url":"https:\/\/persolog.com\/de\/blog\/author\/persolog\/"}]}},"_links":{"self":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/11004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/comments?post=11004"}],"version-history":[{"count":29,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/11004\/revisions"}],"predecessor-version":[{"id":31092,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/11004\/revisions\/31092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/media\/20120"}],"wp:attachment":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/media?parent=11004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/categories?post=11004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/tags?post=11004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}