{"id":22330,"date":"2024-01-19T11:04:53","date_gmt":"2024-01-19T10:04:53","guid":{"rendered":"https:\/\/persolog.com\/?p=22330"},"modified":"2024-01-22T16:50:41","modified_gmt":"2024-01-22T15:50:41","slug":"hybrid-leadership","status":"publish","type":"post","link":"https:\/\/persolog.com\/de\/blog\/hybrid-leadership\/","title":{"rendered":"Hybrid Leadership: Wie erfolgreiche hybride F\u00fchrung gelingen kann"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22330\" class=\"elementor elementor-22330\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69e67da e-con-full e-flex e-con e-parent\" data-id=\"69e67da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83b48c0 elementor-widget elementor-widget-text-editor\" data-id=\"83b48c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fchrungskr\u00e4fte stehen heute vor einer Vielzahl von Herausforderungen, von Digitalisierungsprozessen bis hin zu unsicheren Zukunftsaussichten. Der herk\u00f6mmliche F\u00fchrungsstil st\u00f6\u00dft oft an seine Grenzen, und inmitten des Dauer-Krisenmodus wird deutlich: Hybride F\u00fchrung ist der Schl\u00fcssel, um den Anforderungen der modernen Arbeitswelt gerecht zu werden.<\/p><p>\u201eHybrid work doesn\u2019t happen by chance, and you need to be intentional, proactive and thoughtful to make it work properly. It\u2019s not easy but is doable and the outcomes can be massive\u201d  ~Miroslav Miroslavov, CEO und Mitgr\u00fcnder von OfficeRnD<\/p><p>Oder zu deutsch: \u201eHybride Arbeit entsteht nicht zuf\u00e4llig. Man muss zielgerichtet, proaktiv und durchdacht vorgehen, damit sie richtig funktioniert. Es ist nicht einfach, aber machbar, und die Ergebnisse k\u00f6nnen enorm sein\u201c\n\nDieses Zitat zeigt uns, dass hybride Arbeit und insbesondere hybride F\u00fchrung nur funktionieren kann, wenn man Aufwand in diese investiert, dass es den Aufwand aber wert ist, da so enorme Ergebnisse erzielt werden k\u00f6nnen. Doch wieso sollte man sich jetzt, nach den Einschr\u00e4nkungen im Arbeitsalltag, die mit der Pandemie einhergingen, \u00fcberhaupt noch mit den Themen hybride Arbeit oder hybride F\u00fchrung befassen?<\/p><h4><strong>Hybrides Arbeiten ist attraktiver den je<\/strong><\/h4><p>Studien der Hays AG, die gemeinsam mit dem rheingold Institut durchgef\u00fchrt wurden, zeigen eindeutig, dass hybride F\u00fchrung und hybride Arbeit auch in den n\u00e4chsten Jahren ein Thema bleiben werden, mit welchem sich die Auseinandersetzung lohnt, um eben jene enormen Ergebnisse zu erzielen von denen Miroslavov spricht. So planen beispielsweise 94 % der befragten Unternehmen, dass sie die M\u00f6glichkeit des Homeoffices weiterhin erhalten wollen. Favorisiert wird dabei das hybride Arbeitsmodell: 50 % der Zeit wird im Homeoffice gearbeitet und 50 % der Zeit in Pr\u00e4senz. Auch der L\u00e4nderreport f\u00fcr Deutschland der Employer Brand Research 2023 von randstad  zeigt, dass flexible Arbeitsmodelle wichtig f\u00fcr einen Arbeitgeber sind, denn immerhin 21 % der Befragten geben als Grund f\u00fcr eine K\u00fcndigung oder die Absicht den Arbeitgeber zu wechseln an, dass sie nicht gen\u00fcgend flexible Arbeitsm\u00f6glichkeiten haben.<\/p><h4><strong>Aber womit starte ich als F\u00fchrungskraft, wenn ich mich intensiver mit dem Thema hybride F\u00fchrung auseinandersetzen m\u00f6chte?<\/strong><\/h4><p>Nat\u00fcrlich k\u00f6nnte man bei den Mitarbeitenden ansetzen und diese so \u201ekonditionieren\u201c, dass die hybride Arbeit f\u00fcr einen selbst als F\u00fchrungskraft funktioniert. Die wesentlich gr\u00f6\u00dfere Hebelwirkung entsteht jedoch, wenn man bei sich selbst ansetzt. Die genauen Hebel haben wir bei persolog hierbei als die Folgenden definiert:<\/p><ul><li>Die  eigene Einstellung,<\/li><li>die richtigen Voraussetzungen,<\/li><li>Vertrauen und Verantwortung,<\/li><li>Kommunikation,<\/li><li>Motivation und Wertsch\u00e4tzung,<\/li><li>Teamspirit sowie<\/li><li>mentale Gesundheit.<\/li><\/ul><p>Wenn sich F\u00fchrungskr\u00e4fte Gedanken \u00fcber diese sieben Bereiche machen und stetig hieran arbeiten, dann kann ihre hybride F\u00fchrung immer erfolgreicher werden. In einen dieser Hebel m\u00f6chte ich dir gerne einen Einblick geben:<\/p><h4><strong>Mindset matters \u2013 Die eigene Einstellung<\/strong><\/h4><p>Ein erfolgreiches hybrides F\u00fchrungsmodell erfordert mehr als nur organisatorische Anpassungen des Unternehmens, es verlangt auch eine mentale Verschiebung. F\u00fchrungskr\u00e4fte, die bereit sind, traditionelle Denkweisen der F\u00fchrung \u00fcber Bord zu werfen und sich aktiv auf die neue Herausforderung einzulassen <a href=\"https:\/\/persolog.com\/de\/blog\/mindset-matters\/\" target=\"_blank\" rel=\"noopener\">(fixed mindest vs. growth mindset),<\/a> setzen den Grundstein f\u00fcr effektive hybride F\u00fchrung und sind mit gr\u00f6\u00dferer Wahrscheinlichkeit erfolgreich als diejenigen, die sich vor dem neuen Konzept verschlie\u00dfen. Das Bewusstsein f\u00fcr die individuelle Einstellung, gepr\u00e4gt von Offenheit, Anpassungsf\u00e4higkeit und einem klaren Fokus auf die Bed\u00fcrfnisse des Teams, ist dabei von zentraler Bedeutung. Denn letztendlich sind es nicht nur die Technologien, die den Wandel vorantreiben, sondern die Haltung der F\u00fchrungskr\u00e4fte, die den Weg f\u00fcr eine erfolgreiche hybride Arbeitswelt ebnen.<\/p><p>Wahrscheinlich sagt dir der Begriff selbsterf\u00fcllende Prophezeiung etwas: Dabei handelt es sich um eine Vorhersage, die ihre Erf\u00fcllung selbst bewirkt. Das gleiche Prinzip gilt auch f\u00fcr die eigene Einstellung. Sage ich mir immer, dass hybride F\u00fchrung f\u00fcr mich sowieso nicht funktioniert und die hybride Arbeit sicher in einem riesigen Chaos endet, dann ist die Wahrscheinlichkeit h\u00f6her, dass das eintritt, als wenn ich \u201evorhersage\u201c, dass meine hybride F\u00fchrung sicher ein gro\u00dfer Erfolg wird.<\/p><p>Die Gestaltung erfolgreicher hybrider Arbeit erfordert nicht nur \u00e4u\u00dfere Anpassungen, sondern auch eine positive Einstellung. Durch die bewusste Annahme der Herausforderungen und ein optimistisches Mindset pr\u00e4gen wir nicht nur unseren eigenen Erfolg, sondern auch den Erfolg unserer Teams in der dynamischen Arbeitswelt von heute.<\/p><p>Du m\u00f6chtest tiefer in das Thema der hybriden F\u00fchrung eintauchen? Dann ist <strong><a href=\"https:\/\/academy.persolog.de\/seminar-hybrid-leadership?utm_source=blog&amp;utm_medium=anzeige\">\u201eHybrid Leadership: F\u00fchren in der digitalen Welt\u201c<\/a><\/strong> genau richtig f\u00fcr dich.<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Leaders today face a multitude of challenges, from digitization processes to uncertain future prospects. Conventional leadership styles often reach their limits, and amid the perpetual crisis mode, it becomes evident: Hybrid leadership is the key to meeting the demands of the modern work environment. &#8220;Hybrid work doesn&#8217;t happen by chance, and you need to be [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":22442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1434],"tags":[],"class_list":["post-22330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leadership"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hybrid Leadership: How Successful Hybrid Leadership Can Work - persolog Homepage<\/title>\n<meta name=\"description\" content=\"Mit Hybrid Leadership k\u00f6nnen Herausforderungen wie digitale Prozesse und unsichere Zukunftsaussichten gemeistert werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/persolog.com\/de\/blog\/hybrid-leadership\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hybrid Leadership: How Successful Hybrid Leadership Can Work\" \/>\n<meta property=\"og:description\" content=\"Mit Hybrid Leadership k\u00f6nnen Herausforderungen wie digitale Prozesse und unsichere Zukunftsaussichten gemeistert werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/persolog.com\/de\/blog\/hybrid-leadership\/\" \/>\n<meta property=\"og:site_name\" content=\"persolog Homepage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-19T10:04:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T15:50:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/persolog.com\/wp-content\/uploads\/2024\/01\/AdobeStock_461272130_web-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jana K\u00fcnzel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jana K\u00fcnzel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/\"},\"author\":{\"name\":\"Jana K\u00fcnzel\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/person\\\/d41538d28c338ccef8dfec011f9db82a\"},\"headline\":\"Hybrid Leadership: How Successful Hybrid Leadership Can Work\",\"datePublished\":\"2024-01-19T10:04:53+00:00\",\"dateModified\":\"2024-01-22T15:50:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/\"},\"wordCount\":649,\"publisher\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/AdobeStock_461272130_web-1-scaled.jpg\",\"articleSection\":[\"Leadership\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/\",\"name\":\"Hybrid Leadership: How Successful Hybrid Leadership Can Work - persolog Homepage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/AdobeStock_461272130_web-1-scaled.jpg\",\"datePublished\":\"2024-01-19T10:04:53+00:00\",\"dateModified\":\"2024-01-22T15:50:41+00:00\",\"description\":\"Mit Hybrid Leadership k\u00f6nnen Herausforderungen wie digitale Prozesse und unsichere Zukunftsaussichten gemeistert werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/#primaryimage\",\"url\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/AdobeStock_461272130_web-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/AdobeStock_461272130_web-1-scaled.jpg\",\"width\":2560,\"height\":1340,\"caption\":\"Wie erfolgreiche hybride F\u00fchrung gelingen kann\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/hybrid-leadership\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/persolog.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hybrid Leadership: How Successful Hybrid Leadership Can Work\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"name\":\"persolog\u00ae Homepage\",\"description\":\"Develop organizations through people\",\"publisher\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/persolog.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\",\"name\":\"persolog\u00ae GmbH\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"contentUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"width\":150,\"height\":36,\"caption\":\"persolog\u00ae GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/persolog.persoenlichkeitsentwicklung\\\/?locale=de_DE\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/persolog-gmbh\",\"https:\\\/\\\/www.instagram.com\\\/persolog_\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/person\\\/d41538d28c338ccef8dfec011f9db82a\",\"name\":\"Jana K\u00fcnzel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ad7d980ff514b95953077bda60a2ea4b6b99c88d455a180fb266343331716d?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ad7d980ff514b95953077bda60a2ea4b6b99c88d455a180fb266343331716d?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ad7d980ff514b95953077bda60a2ea4b6b99c88d455a180fb266343331716d?s=96&d=identicon&r=g\",\"caption\":\"Jana K\u00fcnzel\"},\"url\":\"https:\\\/\\\/persolog.com\\\/de\\\/blog\\\/author\\\/jana-kuenzel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hybride F\u00fchrung: Wie erfolgreiche hybride F\u00fchrung funktionieren kann - persolog Homepage","description":"Mit Hybrid Leadership k\u00f6nnen Herausforderungen wie digitale Prozesse und unsichere Zukunftsaussichten gemeistert werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/persolog.com\/de\/blog\/hybrid-leadership\/","og_locale":"de_DE","og_type":"article","og_title":"Hybrid Leadership: How Successful Hybrid Leadership Can Work","og_description":"Mit Hybrid Leadership k\u00f6nnen Herausforderungen wie digitale Prozesse und unsichere Zukunftsaussichten gemeistert werden.","og_url":"https:\/\/persolog.com\/de\/blog\/hybrid-leadership\/","og_site_name":"persolog Homepage","article_publisher":"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","article_published_time":"2024-01-19T10:04:53+00:00","article_modified_time":"2024-01-22T15:50:41+00:00","og_image":[{"width":2560,"height":1340,"url":"https:\/\/persolog.com\/wp-content\/uploads\/2024\/01\/AdobeStock_461272130_web-1-scaled.jpg","type":"image\/jpeg"}],"author":"Jana K\u00fcnzel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Jana K\u00fcnzel","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/#article","isPartOf":{"@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/"},"author":{"name":"Jana K\u00fcnzel","@id":"https:\/\/persolog.com\/#\/schema\/person\/d41538d28c338ccef8dfec011f9db82a"},"headline":"Hybrid Leadership: How Successful Hybrid Leadership Can Work","datePublished":"2024-01-19T10:04:53+00:00","dateModified":"2024-01-22T15:50:41+00:00","mainEntityOfPage":{"@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/"},"wordCount":649,"publisher":{"@id":"https:\/\/persolog.com\/#organization"},"image":{"@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/#primaryimage"},"thumbnailUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2024\/01\/AdobeStock_461272130_web-1-scaled.jpg","articleSection":["Leadership"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/","url":"https:\/\/persolog.com\/blog\/hybrid-leadership\/","name":"Hybride F\u00fchrung: Wie erfolgreiche hybride F\u00fchrung funktionieren kann - persolog Homepage","isPartOf":{"@id":"https:\/\/persolog.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/#primaryimage"},"image":{"@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/#primaryimage"},"thumbnailUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2024\/01\/AdobeStock_461272130_web-1-scaled.jpg","datePublished":"2024-01-19T10:04:53+00:00","dateModified":"2024-01-22T15:50:41+00:00","description":"Mit Hybrid Leadership k\u00f6nnen Herausforderungen wie digitale Prozesse und unsichere Zukunftsaussichten gemeistert werden.","breadcrumb":{"@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/persolog.com\/blog\/hybrid-leadership\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/#primaryimage","url":"https:\/\/persolog.com\/wp-content\/uploads\/2024\/01\/AdobeStock_461272130_web-1-scaled.jpg","contentUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2024\/01\/AdobeStock_461272130_web-1-scaled.jpg","width":2560,"height":1340,"caption":"Wie erfolgreiche hybride F\u00fchrung gelingen kann"},{"@type":"BreadcrumbList","@id":"https:\/\/persolog.com\/blog\/hybrid-leadership\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/persolog.com\/"},{"@type":"ListItem","position":2,"name":"Hybrid Leadership: How Successful Hybrid Leadership Can Work"}]},{"@type":"WebSite","@id":"https:\/\/persolog.com\/#website","url":"https:\/\/persolog.com\/","name":"persolog\u00ae Startseite","description":"Organisationen durch Menschen entwickeln","publisher":{"@id":"https:\/\/persolog.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/persolog.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/persolog.com\/#organization","name":"persolog\u00ae GmbH","url":"https:\/\/persolog.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/","url":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","contentUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","width":150,"height":36,"caption":"persolog\u00ae GmbH"},"image":{"@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","https:\/\/de.linkedin.com\/company\/persolog-gmbh","https:\/\/www.instagram.com\/persolog_\/"]},{"@type":"Person","@id":"https:\/\/persolog.com\/#\/schema\/person\/d41538d28c338ccef8dfec011f9db82a","name":"Jana K\u00fcnzel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a2ad7d980ff514b95953077bda60a2ea4b6b99c88d455a180fb266343331716d?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2ad7d980ff514b95953077bda60a2ea4b6b99c88d455a180fb266343331716d?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ad7d980ff514b95953077bda60a2ea4b6b99c88d455a180fb266343331716d?s=96&d=identicon&r=g","caption":"Jana K\u00fcnzel"},"url":"https:\/\/persolog.com\/de\/blog\/author\/jana-kuenzel\/"}]}},"_links":{"self":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/22330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/comments?post=22330"}],"version-history":[{"count":26,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/22330\/revisions"}],"predecessor-version":[{"id":22441,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/22330\/revisions\/22441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/media\/22442"}],"wp:attachment":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/media?parent=22330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/categories?post=22330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/tags?post=22330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}