{"id":5649,"date":"2013-01-09T14:15:02","date_gmt":"2013-01-09T13:15:02","guid":{"rendered":"https:\/\/beta.persolog.de\/wer-lernt-wie-bei-mcdonalds\/"},"modified":"2024-04-26T12:12:07","modified_gmt":"2024-04-26T10:12:07","slug":"learning-at-mcdonalds","status":"publish","type":"post","link":"https:\/\/persolog.com\/de\/blog\/learning-at-mcdonalds\/","title":{"rendered":"Wie man: Lernen bei McDonald's"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5649\" class=\"elementor elementor-5649\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49847433 e-flex e-con-boxed e-con e-parent\" data-id=\"49847433\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5779a0 elementor-widget elementor-widget-text-editor\" data-id=\"a5779a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>McDonald\u2019s Deutschland hat f\u00fcr die interne Trainerqualifizierung ein speziell entwickeltes Grundlagen- und Aufbauseminar f\u00fcr Mitarbeiter in Trainingspositionen konzipiert. Seit diesem Jahr werden die von persolog entwickelten <a href=\"https:\/\/shop.persolog.com\/persolog-Lehrstil-Profil\/DE-IN800-11-15-V2.2\" target=\"_blank\" rel=\"noopener\">Lern- und Lehrstilprofile<\/a> erstmalig eingesetzt. Damit sollen die Teilnehmer ihr eigenes Lehrverhalten reflektieren und optimieren. So soll gew\u00e4hrleistet werden, dass Seminare teilnehmerorientiert ausgerichtet werden.<\/p>\n\n<h3><strong>Ein Interview mit Philipp Schulz, verantwortlicher Leiter des nationalen Schulungszentrums von McDonald\u2019s Deutschland Inc.<\/strong><\/h3>\n<p>\u00a0<\/p>\n\n<h4><strong>persolog: Welche Herausforderungen im Bereich Training hast du aktuell bei McDonald\u2018s?<\/strong><\/h4>\n\n<p><strong>Philipp Schulz:<\/strong> Unser Anspruch ist es, unsere Mitarbeiter in den Restaurants und in der Verwaltung auf die st\u00e4ndigen Herausforderungen im Alltag vorzubereiten. Neue Produkte, neue Verfahrensmethoden und die Vielzahl an Aufgaben im Restaurant, aber auch in der Verwaltung f\u00fchren dazu, dass unsere Mitarbeiter gefordert sind. Wir unterst\u00fctzen Sie darin.<\/p>\n\n<h4><strong>persolog: Worauf legst du bei der Schulung der Teilnehmer besondere Schwerpunkte?<\/strong><\/h4>\n<p><strong>Philipp Schulz:<\/strong> Um die Teilnehmer bestm\u00f6glich zu qualifizieren und zu motivieren, m\u00fcssen unsere Trainer methodisch und didaktisch professionell vorgehen. Um das zu gew\u00e4hrleisten, haben wir neben Einarbeitungspl\u00e4nen f\u00fcr die Trainer ein eigens entwickeltes Schulungsprogramm aufgestellt, das wir \u201eTraining for Trainers\u201c nennen.<\/p>\n\n<h4><strong>persolog: Wie sieht diese Trainerqualifikation genau aus?<\/strong><\/h4>\n<p><strong>Philipp Schulz:<\/strong> Wir haben ein zweistufiges Programm f\u00fcr unsere Schulungsmitarbeiter entwickelt. Das anf\u00e4ngliche Grundseminar umfasst Pr\u00e4sentationstechniken, Methodik und Didaktik sowie Input von einem angesehenen Theaterregisseur zu K\u00f6rpersprache und Ausdruck. Dies r\u00fcstet unsere Trainer gut aus. Sobald die Teilnehmer Erfahrung sammeln, k\u00f6nnen sie an unserem Aufbauseminar teilnehmen, das unter anderem <a href=\"https:\/\/persolog.com\/de\/blog\/wer-lernt-wie-lerntyp-vs-lernstil\/\" target=\"_blank\" rel=\"noopener\">die Lern- und Lehrstile von persolog<\/a> umfasst<\/p>\n\n<h4><strong>persolog: Wie setzt du das Lern- und Lehrstil-Modell nun konkret ein?<\/strong><\/h4>\n\n<p class=\"translation-block\"><strong>Philipp Schulz:<\/strong> Zun\u00e4chst wiederholen wir die Inhalte aus unserem Basisseminar. Das Gute daran ist, dass die Lern- und Lehrstilprofile direkt darauf aufbauen. Die Perspektive ist, unsere Seminare auf die Teilnehmer auszurichten und dazu ist es gut, wenn man sich unterschiedliche Lernstile vor Augen f\u00fchrt und seinen eigenen Lehrstil darauf ausrichtet. Ein guter Trainer muss flexibel sein und auf die unterschiedlichen Anspr\u00fcche reagieren k\u00f6nnen. Nachdem die Teilnehmer die Profile erarbeitet haben, gehen wir intensiver auf Vor- und Nachteile der Stile ein und \u00fcberlegen, welche Konsequenzen wir f\u00fcr die Zukunft daraus ziehen und erarbeiten dies mit Metaplanw\u00e4nden.<\/p>\n\n<h4><strong>persolog: Wie bist du auf unsere Profile in diesem Zusammenhang aufmerksam geworden?<\/strong><\/h4>\n\n<p><strong>Philipp Schulz:<\/strong> Wir finden es wichtig, dass ein Trainer nicht nur inhaltlich von Zeit zu Zeit Trainings \u00fcberdenkt, sondern auch sein eigenes Trainerverhalten reflektiert. Wir waren deshalb auf der Suche nach einem geeigneten Tool, um dies zu erm\u00f6glichen. Nachdem wir es getestet haben, waren wir begeistert von der Aussagekraft und zugleich von dem einfachen Verst\u00e4ndnis der Inhalte. Dies spiegelt sich mittlerweile auch im Feedback der Teilnehmer wider.<\/p>\n\n<h4><strong>persolog: Eine letzte Frage noch: Verkaufst du durch das Lehr- und Lernstilprofil und dem Training for Trainers, welche du durchf\u00fchrst, mehr Burger?<\/strong><\/h4>\n\n<p><strong>Philipp Schulz:<\/strong> Eine interessante Frage! Das w\u00e4re ein interessantes Forschungsprojekt. Aber wirklich valide und reliable Daten zu bekommen, ist f\u00fcr mich unm\u00f6glich. Wissenschaftlich muss ich diese Frage offenlassen. Auf der anderen Seite glauben wir, dass wir durch unseren erm\u00f6glichungsdidaktischen Ansatz unsere Trainer bestm\u00f6glich qualifizieren, motivieren und dadurch unsere Trainings optimieren. Eins muss ich wirklich sagen: McDonald\u2019s hat eigene angestellte Trainer \u2013 und diese sind Top ausgebildet. Und durch unsere gut geschulten und motivierten Teilnehmer wirkt sich das sicherlich auch auf die komplexen Vorg\u00e4nge im Restaurant aus.<\/p>\n\n<p>\u00a0<\/p>\n\n<p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>McDonald's Deutschland hat ein speziell entwickeltes Basis- und Aufbauseminar f\u00fcr Mitarbeiter in Ausbildungspositionen zur internen Trainerqualifizierung konzipiert. Seit diesem Jahr kommen erstmals die von persolog entwickelten Lern- und Lehrstilprofile zum Einsatz. Damit sollen die Teilnehmer in die Lage versetzt werden, ihr eigenes Lehrverhalten zu reflektieren und zu optimieren. Damit soll sichergestellt werden, dass sich die Seminare an den Teilnehmern orientieren.<\/p>","protected":false},"author":1,"featured_media":20289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1428,1423],"tags":[671,672,432,673,143,28,674,298,675],"class_list":["post-5649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learningcompetence","category-training-world","tag-lehrstil","tag-lernen-und-lehren","tag-lernstil","tag-mcdonalds","tag-persolog","tag-persoenlichkeit","tag-qualifizierung","tag-seminare","tag-trainerausbildung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Learning at McDonalds \u2013 persolog Blog<\/title>\n<meta name=\"description\" content=\"Blog | Learning more about McDonald&#039;s Germany&#039;s new training program. Enhance your teaching methods and optimize your instructional behavior.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/persolog.com\/de\/blog\/learning-at-mcdonalds\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to: Learning at McDonald&#039;s\" \/>\n<meta property=\"og:description\" content=\"Blog | Learning more about McDonald&#039;s Germany&#039;s new training program. Enhance your teaching methods and optimize your instructional behavior.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/persolog.com\/de\/blog\/learning-at-mcdonalds\/\" \/>\n<meta property=\"og:site_name\" content=\"persolog Homepage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-09T13:15:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T10:12:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/persolog.com\/wp-content\/uploads\/2013\/01\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"persolog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"persolog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/\"},\"author\":{\"name\":\"persolog\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/person\\\/f281c4aed52bf5e01f0bb326bbcf1ae9\"},\"headline\":\"How to: Learning at McDonald&#8217;s\",\"datePublished\":\"2013-01-09T13:15:02+00:00\",\"dateModified\":\"2024-04-26T10:12:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/\"},\"wordCount\":592,\"publisher\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg\",\"keywords\":[\"Lehrstil\",\"Lernen und Lehren\",\"Lernstil\",\"McDonald`s\",\"persolog\",\"Pers\u00f6nlichkeit\",\"Qualifizierung\",\"Seminare\",\"Trainerausbildung\"],\"articleSection\":[\"Learning competence\",\"Training world\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/\",\"name\":\"Learning at McDonalds \u2013 persolog Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg\",\"datePublished\":\"2013-01-09T13:15:02+00:00\",\"dateModified\":\"2024-04-26T10:12:07+00:00\",\"description\":\"Blog | Learning more about McDonald's Germany's new training program. Enhance your teaching methods and optimize your instructional behavior.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg\",\"width\":2560,\"height\":1708,\"caption\":\"Wer lernt wie bei McDonald`s?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/persolog.com\\\/blog\\\/learning-at-mcdonalds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/persolog.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to: Learning at McDonald&#8217;s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#website\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"name\":\"persolog\u00ae Homepage\",\"description\":\"Develop organizations through people\",\"publisher\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/persolog.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#organization\",\"name\":\"persolog\u00ae GmbH\",\"url\":\"https:\\\/\\\/persolog.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"contentUrl\":\"https:\\\/\\\/persolog.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/persolog-logo-refreshed.svg\",\"width\":150,\"height\":36,\"caption\":\"persolog\u00ae GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/persolog.persoenlichkeitsentwicklung\\\/?locale=de_DE\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/persolog-gmbh\",\"https:\\\/\\\/www.instagram.com\\\/persolog_\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/persolog.com\\\/#\\\/schema\\\/person\\\/f281c4aed52bf5e01f0bb326bbcf1ae9\",\"name\":\"persolog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g\",\"caption\":\"persolog\"},\"sameAs\":[\"https:\\\/\\\/rev-proxy-other.prod.persolog.online\"],\"url\":\"https:\\\/\\\/persolog.com\\\/de\\\/blog\\\/author\\\/persolog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lernen bei McDonalds - persolog Blog","description":"Blog | Erfahren Sie mehr \u00fcber das neue Schulungsprogramm von McDonald's Deutschland. Verbessern Sie Ihre Lehrmethoden und optimieren Sie Ihr Lehrverhalten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/persolog.com\/de\/blog\/learning-at-mcdonalds\/","og_locale":"de_DE","og_type":"article","og_title":"How to: Learning at McDonald's","og_description":"Blog | Learning more about McDonald's Germany's new training program. Enhance your teaching methods and optimize your instructional behavior.","og_url":"https:\/\/persolog.com\/de\/blog\/learning-at-mcdonalds\/","og_site_name":"persolog Homepage","article_publisher":"https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","article_published_time":"2013-01-09T13:15:02+00:00","article_modified_time":"2024-04-26T10:12:07+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/persolog.com\/wp-content\/uploads\/2013\/01\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg","type":"image\/jpeg"}],"author":"persolog","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"persolog","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/#article","isPartOf":{"@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/"},"author":{"name":"persolog","@id":"https:\/\/persolog.com\/#\/schema\/person\/f281c4aed52bf5e01f0bb326bbcf1ae9"},"headline":"How to: Learning at McDonald&#8217;s","datePublished":"2013-01-09T13:15:02+00:00","dateModified":"2024-04-26T10:12:07+00:00","mainEntityOfPage":{"@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/"},"wordCount":592,"publisher":{"@id":"https:\/\/persolog.com\/#organization"},"image":{"@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/#primaryimage"},"thumbnailUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2013\/01\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg","keywords":["Lehrstil","Lernen und Lehren","Lernstil","McDonald`s","persolog","Pers\u00f6nlichkeit","Qualifizierung","Seminare","Trainerausbildung"],"articleSection":["Learning competence","Training world"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/","url":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/","name":"Lernen bei McDonalds - persolog Blog","isPartOf":{"@id":"https:\/\/persolog.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/#primaryimage"},"image":{"@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/#primaryimage"},"thumbnailUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2013\/01\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg","datePublished":"2013-01-09T13:15:02+00:00","dateModified":"2024-04-26T10:12:07+00:00","description":"Blog | Erfahren Sie mehr \u00fcber das neue Schulungsprogramm von McDonald's Deutschland. Verbessern Sie Ihre Lehrmethoden und optimieren Sie Ihr Lehrverhalten.","breadcrumb":{"@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/#primaryimage","url":"https:\/\/persolog.com\/wp-content\/uploads\/2013\/01\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg","contentUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2013\/01\/AdobeStock_371502121_Editorial_Use_Only-scaled.jpeg","width":2560,"height":1708,"caption":"Wer lernt wie bei McDonald`s?"},{"@type":"BreadcrumbList","@id":"https:\/\/persolog.com\/blog\/learning-at-mcdonalds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/persolog.com\/"},{"@type":"ListItem","position":2,"name":"How to: Learning at McDonald&#8217;s"}]},{"@type":"WebSite","@id":"https:\/\/persolog.com\/#website","url":"https:\/\/persolog.com\/","name":"persolog\u00ae Startseite","description":"Organisationen durch Menschen entwickeln","publisher":{"@id":"https:\/\/persolog.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/persolog.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/persolog.com\/#organization","name":"persolog\u00ae GmbH","url":"https:\/\/persolog.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/","url":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","contentUrl":"https:\/\/persolog.com\/wp-content\/uploads\/2023\/05\/persolog-logo-refreshed.svg","width":150,"height":36,"caption":"persolog\u00ae GmbH"},"image":{"@id":"https:\/\/persolog.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/persolog.persoenlichkeitsentwicklung\/?locale=de_DE","https:\/\/de.linkedin.com\/company\/persolog-gmbh","https:\/\/www.instagram.com\/persolog_\/"]},{"@type":"Person","@id":"https:\/\/persolog.com\/#\/schema\/person\/f281c4aed52bf5e01f0bb326bbcf1ae9","name":"persolog","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d3c2ef17d98a8e797c08436ef32e8a53835586b17d59f2d2d5ff5616a3e7055?s=96&d=identicon&r=g","caption":"persolog"},"sameAs":["https:\/\/rev-proxy-other.prod.persolog.online"],"url":"https:\/\/persolog.com\/de\/blog\/author\/persolog\/"}]}},"_links":{"self":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/5649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/comments?post=5649"}],"version-history":[{"count":19,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/5649\/revisions"}],"predecessor-version":[{"id":25802,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/posts\/5649\/revisions\/25802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/media\/20289"}],"wp:attachment":[{"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/media?parent=5649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/categories?post=5649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/persolog.com\/de\/wp-json\/wp\/v2\/tags?post=5649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}